{"id":5090,"date":"2025-11-02T22:11:46","date_gmt":"2025-11-03T03:11:46","guid":{"rendered":"https:\/\/thechallengecoach.com\/?post_type=tribe_events&#038;p=5090"},"modified":"2025-11-02T22:11:46","modified_gmt":"2025-11-03T03:11:46","slug":"week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025","status":"publish","type":"tribe_events","link":"https:\/\/thechallengecoach.com\/fr\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025","title":{"rendered":"Semaine 3 PEP Red\u00e9finir la discipline : Un cours en ligne de 4 semaines pour les parents - novembre 2025"},"content":{"rendered":"<p data-children-count=\"0\">Parents, croyez-vous que vos enfants n'agiront pas comme vous le souhaitez si vous ne les punissez pas pour les contraindre \u00e0 une certaine forme d'ob\u00e9issance... ou si vous faites le contraire en leur promettant des r\u00e9compenses en cas de bon comportement ?<\/p>\n<p data-children-count=\"0\">Vous cherchez de nouvelles id\u00e9es pour mettre fin au cycle des disputes, des n\u00e9gociations, des punitions et des carottes ?<\/p>\n<p data-children-count=\"0\">PEP's\u00a0<em>Red\u00e9finir la discipline : Un guide sans artifices pour \u00e9lever des enfants responsables et respectueux<\/em>\u00a0vous aidera \u00e0 retrouver l'harmonie, la coop\u00e9ration et les liens au sein de votre famille.<\/p>\n<p data-children-count=\"0\">Ce cours de 30 jours permet d'aborder les situations et les comportements probl\u00e9matiques sous un angle diff\u00e9rent. Il s'agit d'une approche \u00e9prouv\u00e9e qui permet de construire des relations avec plus de joie et moins de frictions... et qui permet \u00e0 votre enfant de s'\u00e9panouir.<\/p>\n<p data-children-count=\"0\">D\u00e9couvrez un nouveau r\u00f4le de coach aupr\u00e8s de vos enfants et aidez-les \u00e0 s'engager sur la voie de l'autodiscipline.<\/p>\n<p data-children-count=\"0\"><em>Red\u00e9finir la discipline<\/em>\u00a0s'appuie sur les principes et les strat\u00e9gies couverts par la\u00a0<em>Encouragement : D\u00e9velopper la confiance de votre enfant de l'int\u00e9rieur\u00a0<\/em><span class=\"redactor-invisible-space\">en ligne. Il est destin\u00e9 aux parents d'enfants d'\u00e2ge pr\u00e9scolaire jusqu'aux adolescents.<\/span><\/p>\n<p data-children-count=\"0\"><strong>Dates des cours<\/strong><\/p>\n<p>Du vendredi 31 octobre au vendredi 5 d\u00e9cembre 2025 (nous prendrons la semaine de Thanksgiving)<\/p>\n<p data-children-count=\"0\"><strong>Fonctionnement de la classe<\/strong><\/p>\n<ul data-children-count=\"0\">\n<li><strong>Chaque semaine, le vendredi, \u00e0 partir du 31 octobre<\/strong>, vous recevrez un nouveau\u00a0<strong>Le\u00e7on vid\u00e9o<\/strong>\u00a0\u00e0 regarder \u00e0 votre convenance sur n'importe quel appareil !<\/li>\n<li>Vous recevrez \u00e9galement\u00a0<strong>\"Essayez ceci \u00e0 la maison\"<\/strong>\u00a0des exercices, des documents et des articles pertinents. Pour compl\u00e9ter le mat\u00e9riel hebdomadaire, il faut\u00a0<strong>moins de 20 minutes par semaine<\/strong>.<\/li>\n<li><strong>Discussions hebdomadaires en ligne<\/strong>\u00a0avec l'instructeur de la classe ont lieu le\u00a0<strong>Mercredi\u00a0<\/strong><strong>soir\u00e9es<\/strong><strong>\u00a0\u00e0 20h30 ET \u00e0 partir du 5 novembre.<br \/>\n<\/strong><\/li>\n<li><strong>Sections de commentaires\u00a0<\/strong>sur chaque page vid\u00e9o est mod\u00e9r\u00e9 par l'instructeur du cours - posez vos questions et communiquez avec d'autres parents.<\/li>\n<li>Vid\u00e9os, documents et mat\u00e9riel de cours\u00a0<strong>\u00e0 votre disposition pendant un an\u00a0<\/strong>\u00e0 examiner et \u00e0 r\u00e9examiner si n\u00e9cessaire.<\/li>\n<\/ul>\n<p data-children-count=\"0\"><strong>Ce cours comprend<\/strong><\/p>\n<p data-children-count=\"0\"><strong>6 le\u00e7ons vid\u00e9o didactiques\u00a0<\/strong>(de 7 \u00e0 14 minutes chacune) et regorgent d'astuces et de conseils pratiques \u00e0 mettre en \u0153uvre imm\u00e9diatement. Les le\u00e7ons vid\u00e9o comprennent des jeux de r\u00f4le afin que vous puissiez voir des exemples r\u00e9els de ce qu'il faut dire et faire, et de ce qu'il ne faut PAS dire et faire !<\/p>\n<ul data-children-count=\"0\">\n<li>Semaine 1 : Pourquoi les punitions et les r\u00e9compenses ne fonctionnent pas \/ Cons\u00e9quences naturelles<\/li>\n<li>Semaine 2 : Introduction aux cons\u00e9quences logiques<\/li>\n<li>Semaine 3 : Comment utiliser les cons\u00e9quences logiques \"sur le moment\" (y compris l'art de la r\u00e9solution de probl\u00e8mes qui change la donne)<\/li>\n<li>Semaine 4 : Trois pi\u00e8ges courants et trois conseils parentaux pour r\u00e9ussir<\/li>\n<\/ul>\n<p data-children-count=\"0\"><strong>Exercices hebdomadaires \"Essayez ceci \u00e0 la maison\".<\/strong>\u00a0afin que vous puissiez mettre chaque le\u00e7on en pratique imm\u00e9diatement avec votre famille.<\/p>\n<p data-children-count=\"0\"><strong>Articles d'actualit\u00e9 sur la parentalit\u00e9 PEP<\/strong>\u00a0afin que vous puissiez approfondir les sujets.<\/p>\n<p data-children-count=\"0\"><strong>Impressions pratiques\u00a0<\/strong>avec des exemples et un langage que vous pouvez utiliser avec vos enfants, et que vous pouvez afficher \u00e0 proximit\u00e9 pour vous maintenir sur la bonne voie.<\/p>\n<p data-children-count=\"0\"><strong>4 Discussions en classe en direct et en ligne\u00a0<\/strong>avec votre instructeur PEP qui r\u00e9pondra \u00e0 vos questions (vous pouvez les poser \u00e0 l'avance).<\/p>\n<p data-children-count=\"0\"><strong>Sections de commentaires\u00a0<\/strong>o\u00f9 vous recevrez les conseils de la semaine et obtiendrez des r\u00e9ponses \u00e0 vos questions.<\/p>\n<p data-children-count=\"0\"><strong>Combien de temps cela prendra-t-il ?<\/strong><\/p>\n<p data-children-count=\"0\">\n<p data-children-count=\"0\"><strong>Cela d\u00e9pend de vous.\u00a0<\/strong>L'examen des vid\u00e9os et des documents p\u00e9dagogiques prendra environ une heure par semaine. Les\u00a0<em>Essayez-le \u00e0 la maison\u00a0<\/em>Les exercices sont con\u00e7us pour s'int\u00e9grer dans votre vie quotidienne et l'am\u00e9liorer. La discussion en classe dure une heure par semaine et vous pouvez la rejoindre en direct pour poser une question ou la poster dans la section des commentaires.<\/p>\n<p data-children-count=\"0\">Nous savons que modifier vos strat\u00e9gies parentales demande beaucoup de temps et d'efforts. C'est pourquoi nous avons int\u00e9gr\u00e9 les sections Discussions de classe et Commentaires en ligne afin que vous puissiez poser des questions.<strong>.<\/strong>\u00a0<strong>Comme pour toute nouvelle habitude, la t<\/strong><strong>Plus vous participez, plus vous en profitez.<\/strong><\/p>\n<p data-children-count=\"0\"><strong>Que faire si je ne suis pas satisfait de ce cours ?<\/strong><\/p>\n<p data-children-count=\"0\">Si vous n'\u00eates pas satisfait de votre achat, contactez-nous dans les 30 premiers jours et nous vous rembourserons.<\/p>\n<p data-children-count=\"0\"><strong>\u00c0 qui s'adresse ce cours ?<\/strong><\/p>\n<p data-children-count=\"0\">Les concepts fondamentaux enseign\u00e9s dans ce cours s'appliquent aux parents d'enfants de la maternelle \u00e0 l'adolescence - en fait, ces concepts s'appliquent \u00e0 toutes les relations !<\/p>\n<p data-children-count=\"0\"><strong>NOTE :<\/strong>\u00a0Si vous avez besoin d'un certificat d'ach\u00e8vement pour montrer que vous avez suivi ce cours pour parents, un certificat est automatiquement g\u00e9n\u00e9r\u00e9 lorsque vous terminez le cours.<\/p>\n<h2>Votre instructeur<\/h2>\n<div class=\"row\">\n<div class=\"col-lg-3 col-md-4 col-sm-4 text-center\"><img decoding=\"async\" class=\"large-img-rounded img-responsive tc-smart-loaded\" src=\"https:\/\/static-media.hotmart.com\/-hMWrlD5qXtbmsgsvOugTVREaVs=\/0x0\/https:\/\/uploads.teachablecdn.com\/attachments\/RKKcfnMSume9LWuP9kfT_Pascale+Brady.jpg\" alt=\"Pascale Brady\" \/>&nbsp;<\/p>\n<div class=\"author-name\">Pascale Brady<\/div>\n<\/div>\n<div class=\"col-lg-9 col-md-8 col-sm-8\">\n<p>Pascale est \u00e9ducatrice parentale agr\u00e9\u00e9e par le Programme d'encouragement des parents. Elle est devenue veuve et m\u00e8re c\u00e9libataire lorsque ses deux filles avaient 10 et 12 ans. Pascale enseigne et d\u00e9veloppe les cours de parentalit\u00e9 du PEP depuis pr\u00e8s de 20 ans.<\/p>\n<p>En suivant les cours du PEP, Pascale s'est familiaris\u00e9e avec la psychologie d'Alfred Adler, qui constitue le fondement du programme d'\u00e9ducation parentale positive du PEP. Elle est devenue The Challenge Coach, un coach de vie et d'affaires, en 2005 et utilise les outils adl\u00e9riens dans son coaching individuel et d'entreprise. En plus d'\u00eatre adl\u00e9rienne, Pascale est fran\u00e7aise, allemande et am\u00e9ricaine, et travaille couramment dans ces quatre langues.<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Parents, do you believe your kids won\u2019t act the way you want them to unless you use punishments to force them into some sort of obedience\u2026 or do the opposite [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3959,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5090","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/fr\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"Parents, do you believe your kids won\u2019t act the way you want them to unless you use punishments to force them into some sort of obedience\u2026 or do the opposite [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/fr\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/logo-footer.png\" \/>\n\t<meta property=\"og:image:width\" content=\"365\" \/>\n\t<meta property=\"og:image:height\" content=\"138\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\",\"name\":\"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo-footer.png\",\"datePublished\":\"2025-11-03T03:11:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo-footer.png\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo-footer.png\",\"width\":365,\"height\":138},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/fr\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach","og_description":"Parents, do you believe your kids won\u2019t act the way you want them to unless you use punishments to force them into some sort of obedience\u2026 or do the opposite [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/fr\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","og_image":[{"width":365,"height":138,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/logo-footer.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@pascalebrady","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025","url":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025","name":"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025 &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/logo-footer.png","datePublished":"2025-11-03T03:11:46+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/logo-footer.png","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/logo-footer.png","width":365,"height":138},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/event\/week-3-pep-redefining-discipline-a-4-week-online-class-for-parents-november-2025#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/thechallengecoach.com\/events\/"},{"@type":"ListItem","position":3,"name":"Week 3 PEP Redefining Discipline: A 4-Week Online Class for Parents \u2013 November 2025"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"La coach du d\u00e9fi","description":"Transformer les d\u00e9fis en croissance et succ\u00e8s","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"La coach du d\u00e9fi","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events\/5090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events\/5090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media\/3959"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media?parent=5090"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tags?post=5090"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=5090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}