{"id":10000579,"date":"2026-03-24T14:39:40","date_gmt":"2026-03-24T19:39:40","guid":{"rendered":"https:\/\/thechallengecoach.com\/?post_type=tribe_events&#038;p=5590"},"modified":"2026-03-24T14:39:40","modified_gmt":"2026-03-24T19:39:40","slug":"cours-de-parentalite-positive-2","status":"publish","type":"tribe_events","link":"https:\/\/thechallengecoach.com\/fr\/event\/cours-de-parentalite-positive-2\/2026-04-01","title":{"rendered":"COURS DE PARENTALIT\u00c9 POSITIVE"},"content":{"rendered":"<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<div>Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes ? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez ? Et finissez-vous r\u00e9guli\u00e8rement soit par c\u00e9der aux exigences de vos enfants, soit par perdre les p\u00e9dales ou, pire, \u201cp\u00eater les plombs\u201d ?....<br \/>\n<br aria-hidden=\"true\" \/>Venez apprendre ce que c'est que la parentalit\u00e9 positive, un syst\u00e8me d'\u00e9ducation parentale bas\u00e9 sur la psychologie de Alfred Adler, et qui conduit \u00e0 une meilleure communication et coop\u00e9ration entre les parents et les enfants, tout en encourageant des limites fermes et des responsabilit\u00e9s partag\u00e9es.<br \/>\n<br aria-hidden=\"true\" \/>Vous repartirez avec des outils concrets, applicables imm\u00e9diatement, et qui conduiront \u00e0 un environnement familial non seulement plus paisible mais \u00e9galement plus harmonieux.<br \/>\n<br aria-hidden=\"true\" \/>Ce cours sera participatif, interactif, et peut changer la vie radicalement.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong data-stringify-type=\"bold\">POURQUOI ?<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">Une des choses qu'on ne nous apprend pas \u00e0 l'\u00e9cole, c'est comment \u00eatre parent. C'est bien dommage ... car c'est un des jobs les plus difficiles de la terre et un de ceux avec le plus de cons\u00e9quences et d'impact. Nos choix de parentalit\u00e9 sont donc bas\u00e9s soit sur nos exp\u00e9riences d'enfant (on fait comme ont fait nos parents, ou au contraire on fait l'inverse !), et\/ou on lit et on s'informe du mieux qu'on peut pour essayer de trouver son propre chemin. Dans tous les cas, on t\u00e2tonne pas mal et on s'en sort du mieux qu'on peut. \u00c7a ne serait pas mieux avec un bon mode d'emploi ?<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlock\">\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/e8e76759-883a-74bf-08b7-e5ea1b19b958.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>POUR QUI ?<\/strong><\/h3>\n<h4>Tout adulte francophone (*) qui s'occupe d'enfants \u00e2g\u00e9s de 2 \u00e0 18 ans (parents, futurs parents, grands-parents, nannys ou nounous, professeurs des \u00e9coles, directeurs\/trices de garderie etc.).<br aria-hidden=\"true\" \/>(*) Les cours seront en langue fran\u00e7aise<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/39cda3aa-a06f-b442-5873-28a3648a2a02.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>QUAND ?<\/strong><\/h3>\n<h4>Les mercredis soirs \u00e0 20h EST (cours de 75 minutes - heure de New York)<br aria-hidden=\"true\" \/>Du mercredi 25 mars 2026 au 13 mai 2026<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/0faf7744-0839-e4f5-4574-0225c95bdb52.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>O\u00d9 ?<\/strong><\/h3>\n<h4>Sur zoom ! Les cours seront enregistr\u00e9s au cas o\u00f9 vous seriez oblig\u00e9 d'en rater un (mais la participation en personne est fortement recommand\u00e9e).<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>CONTENU<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnBoxedTextBlock\">\n<div class=\"mcnBoxedTextBlockInner\">\n<div class=\"mcnBoxedTextBlockColumn\">\n<div class=\"mcnTextContentContainer mcnTextContent\">\n<div><strong>Session 1<\/strong><br \/>\nIntroductions et Objectifs - Styles de parentalite<\/div>\n<div><strong>Session 2<\/strong><br \/>\nLe d\u00e9veloppement de la personnalit\u00e9<\/div>\n<div><strong>Session 3<\/strong><br \/>\nD\u00e9couragement\/Encouragement<\/div>\n<div><strong>Session 4<\/strong><br \/>\nLimites et cons\u00e9quences<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnBoxedTextBlockColumn\">\n<div class=\"mcnTextContentContainer mcnTextContent\">\n<div><strong>Session 5<\/strong><br \/>\nComprendre les comportements de l'enfant<br \/>\n<br aria-hidden=\"true\" \/><strong>Session 6<\/strong><br \/>\nCorriger les comportements - Formation<br \/>\n<br aria-hidden=\"true\" \/><strong>Session 7<\/strong><br \/>\nCommunication - Ecoute<\/div>\n<div><strong>Session 8<\/strong><br \/>\nRevue : compilation et Conseil de famille<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>CO\u00dbT<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div class=\"mcnTextContent\">Pour ces 8 sessions de 75 minutes (total de 10 heures de contenu) :<br aria-hidden=\"true\" \/>$199 (soit $20\/heure)<\/p>\n<p><b><i>IMPORTANT : <\/i><\/b><i>Notre intention et souhait est d'offrir ce programme au plus grand nombre. Si vous \u00eates int\u00e9r\u00e9ss\u00e9(e) et souhaitez nous rejoindre mais que ce co\u00fbt est prohibitif pour vous--pour quelque raison que ce soit-- des tarifs r\u00e9duits sont offerts. Merci de contacter Pascale directement pour en discuter.<\/i><\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>PAR QUI ?<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">Ce cours vous est offert par Pascale Brady, <a href=\"https:\/\/thechallengecoach.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/thechallengecoach.com\/\">La coach du d\u00e9fi<\/a>. Pascale est une coach de vie et d'affaire certifi\u00e9e (CPPC, PCC) et \u00e9galement \u00c9ducatrice Certifi\u00e9e de Parentalit\u00e9 Adl\u00e9rienne par PEP (le\u00a0<a href=\"https:\/\/pepparent.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/pepparent.org\/\">Programme d&#039;encouragement des parents<\/a>) et\u00a0<a href=\"https:\/\/positivediscipline.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/positivediscipline.org\/\">Discipline positive<\/a>\u00a0avec plus de 20 ans d'exp\u00e9rience en coaching et parentalit\u00e9.<\/div>\n<\/div>\n<div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h4 class=\"null\"><strong>Une petite intro \u00e0 propos du cours et les infos pratiques<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnButtonBlock mcnButtonBlockInner\">\n<div><a id=\"0\" class=\"mcnButtonContentContainer mcnButton\" title=\"Une petite intro ICI\" href=\"https:\/\/us02web.zoom.us\/rec\/play\/MQUPPEpcKookJ1GlP74Ku2yI_iT5zNPkFOik3flUw5uGazi4OCyhp1m1C5_WdocjK_R6lInWeYRuyfow.jBTiKG_qW6eDWfMP?eagerLoadZvaPages=sidemenu.billing.plan_management&amp;accessLevel=meeting&amp;canPlayFromShare=true&amp;from=my_recording&amp;startTime=1759783586000&amp;componentName=rec-play&amp;originRequestUrl=https%3A%2F%2Fus02web.zoom.us%2Frec%2Fshare%2FdcaddhxdGxAjI0AyfNKNDsdDEPPvyqvP2kFippzZwBke34MnVdkWtWcCg2aho6K4.Pko04RaDRpASBOjm%3FstartTime%3D1759783586000%26fbclid%3DIwY2xjawNZwg5leHRuA2FlbQIxMABicmlkETFVRm50M05ManpPTlVKcXpVAR5WAXXVCd7J5-Qi-vi6O956erYGk_MEfCwT3JrBp2QFW04s-AVQ5uMHyYzasg_aem_cQfkXygNqccNZ3tPXfEXMQ\" target=\"_blank\" rel=\"noopener\">Une petite intro ICI<\/a><\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<div><strong>Code d'acc\u00e8s : %g46aMUE<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5050,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":{"0":"post-10000579","1":"tribe_events","2":"type-tribe_events","3":"status-publish","4":"has-post-thumbnail","6":"tribe-recurring-event","7":"tribe-recurring-event-parent","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/fr\/event\/cours-de-parentalite-positive-2\/2026-04-01\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/fr\/event\/cours-de-parentalite-positive-2\/2026-04-01\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01\",\"name\":\"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"datePublished\":\"2026-03-24T19:39:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"In a moment of joy, a young girl gives a thumbs-up in response to encouragement, highlighting positive reinforcement during her learning process.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-01#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COURS DE PARENTALIT\u00c9 POSITIVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/fr\/event\/cours-de-parentalite-positive-2\/2026-04-01\/","og_locale":"fr_FR","og_type":"article","og_title":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","og_description":"Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/fr\/event\/cours-de-parentalite-positive-2\/2026-04-01\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","og_image":[{"width":2560,"height":1707,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@pascalebrady","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01","url":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01","name":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","datePublished":"2026-03-24T19:39:40+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","width":2560,"height":1707,"caption":"In a moment of joy, a young girl gives a thumbs-up in response to encouragement, highlighting positive reinforcement during her learning process."},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-01#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/thechallengecoach.com\/events\/"},{"@type":"ListItem","position":3,"name":"COURS DE PARENTALIT\u00c9 POSITIVE"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"La coach du d\u00e9fi","description":"Transformer les d\u00e9fis en croissance et succ\u00e8s","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"La coach du d\u00e9fi","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events\/10000579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events\/10000579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media\/5050"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media?parent=10000579"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tags?post=10000579"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=10000579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}