{"id":3358,"date":"2021-12-14T13:20:31","date_gmt":"2021-12-14T18:20:31","guid":{"rendered":"https:\/\/thechallengecoach.com\/?p=3358"},"modified":"2022-01-13T08:44:07","modified_gmt":"2022-01-13T13:44:07","slug":"year-in-review","status":"publish","type":"post","link":"https:\/\/thechallengecoach.com\/fr\/year-in-review","title":{"rendered":"2021 - Bilan de l'ann\u00e9e"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-1024x683.png\" alt=\"\" class=\"wp-image-3364\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-1024x683.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-600x400.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-300x200.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-768x512.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-18x12.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-570x380.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\"><em><span style=\"color:#088483\" class=\"has-inline-color\">\"La vie est comme un miroir, souriez-lui et il vous sourit en retour.\"<\/span><\/em><\/p>\n\n\n\n<p>Je ne sais pas ce qu'il en est pour vous, mais l'ann\u00e9e a encore \u00e9t\u00e9 difficile... Entre Covid sur le devant de la sc\u00e8ne et le changement climatique en arri\u00e8re-plan, o\u00f9 que vous soyez dans le monde, personne ne peut \u00e9chapper aux difficult\u00e9s que pose la p\u00e9riode actuelle.<br><br>Il existe heureusement de nombreux outils \u00e0 notre disposition pour faire face aux p\u00e9riodes difficiles de la vie, et deux de mes pr\u00e9f\u00e9r\u00e9s - comme vous le savez maintenant si vous avez lu ces articles de blog - sont les suivants <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=be04ceadb5&amp;e=1980597a3c\">conscience<\/a> et en se concentrant sur <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=16dab12882&amp;e=1980597a3c\">le positif<\/a>. Le joyeux bonhomme de neige de l'image ci-dessus vous fait-il sourire ? J'esp\u00e8re bien que oui. Saviez-vous que lorsque nous sourions, activant ainsi les 42 muscles de notre visage, le cerveau lib\u00e8re diverses substances chimiques, dont les endorphines, qui procurent un sentiment de bien-\u00eatre ? Que nous ayons envie de sourire ou non, le fait d'afficher un sourire sur notre visage peut modifier nos \u00e9motions et les rendre plus positives. Et la cerise sur le g\u00e2teau ? C'est contagieux ! Gr\u00e2ce aux neurones miroirs de notre cerveau, lorsque nous sourions, nous contribuons \u00e0 rendre les autres plus heureux.<\/p>\n\n\n\n<p>Essayez : la prochaine fois que vous serez seul et que vous aurez le cafard, souriez, fermez les yeux et sentez votre corps et vos \u00e9motions changer litt\u00e9ralement. Ou encore, la prochaine fois que vous serez au milieu d'une dispute avec quelqu'un... commencez \u00e0 sourire et observez ce qui se passe.<br><br>Alors... en cas d'\u00e9chec, n'oubliez pas de sourire. C'est l'outil d'auto-assistance le plus simple et le plus accessible qui soit !<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland.jpg\" alt=\"\" class=\"wp-image-3361\" width=\"565\" height=\"424\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland.jpg 825w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland-600x450.jpg 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland-300x225.jpg 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland-768x576.jpg 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland-16x12.jpg 16w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Dec-Woodland-570x428.jpg 570w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/figure><\/div>\n\n\n\n<p>L'ann\u00e9e 2021 touche \u00e0 sa fin. C'est toujours le moment de faire une pause et de faire le point sur ce qui s'est pass\u00e9 au cours de l'ann\u00e9e \u00e9coul\u00e9e avant de traverser le pont pour entrer dans la nouvelle ann\u00e9e.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><span style=\"color:#088483\" class=\"has-inline-color\">\u201cFaites une pause et d\u00e9tendez-vous, car c'est la p\u00e9riode de l'ann\u00e9e o\u00f9 l'on se r\u00e9jouit, o\u00f9 l'on fait la f\u00eate et o\u00f9 l'on se sent r\u00e9compens\u00e9.\u201d<\/span><\/em><\/p>\n\n\n\n<p>Avec mes clients, nous profitons de cette p\u00e9riode de fin d'ann\u00e9e pour faire une pause et regarder en arri\u00e8re :<br>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qu'est-ce qui a \u00e9t\u00e9 positif ? Quelles ont \u00e9t\u00e9 les r\u00e9ussites et comment ont-elles \u00e9t\u00e9 obtenues ? Veillez \u00e9galement \u00e0 prendre un moment pour c\u00e9l\u00e9brer les victoires avant de passer \u00e0 la phase suivante de la r\u00e9flexion.<\/li><li>Examinez ensuite les d\u00e9fis ou les obstacles rencontr\u00e9s et les enseignements qui en ont \u00e9t\u00e9 tir\u00e9s.<\/li><\/ul>\n\n\n\n<p>Si vous n'avez pas de coach avec qui mener cette r\u00e9flexion, vous pouvez toujours <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=142c55acf3&amp;e=1980597a3c\">appelez-moi<\/a> \ud83d\ude09 ou vous pouvez le faire avec un ami, ou m\u00eame seul en \u00e9crivant dans un journal. Il s'agit d'un autre moment de pleine conscience, ainsi que d'un moment de d\u00e9tente. <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=8f0cec5573&amp;e=1980597a3c\">l'amour bienveillant<\/a>, Il s'agit d'un temps de r\u00e9flexion, d'appr\u00e9ciation de soi, de c\u00e9l\u00e9bration et d'apprentissage.<br>&nbsp;<br>Chez The Challenge Coach, nous c\u00e9l\u00e9brons quelques-uns des succ\u00e8s de 2021 :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Le lancement r\u00e9ussi et l'accueil chaleureux d'une lettre d'information mensuelle et de cet article de blog,<\/li><li>Un site web disponible en trois langues (anglais, fran\u00e7ais et allemand),<\/li><li>Une nouvelle boutique en ligne proposant des produits mignons et inspirants,<\/li><li>Une communication beaucoup plus active et organis\u00e9e par le biais de notre site web et des m\u00e9dias sociaux,<\/li><li>Une nouvelle pr\u00e9sence sur le circuit des podcasts.<\/li><\/ul>\n\n\n\n<p>Mais tout cela n'aurait pas de sens sans votre soutien ! Merci beaucoup \u00e0 chacun d'entre vous pour votre gentillesse et votre enthousiasme.&nbsp;<br><br>Dans de nombreux pays et communaut\u00e9s du monde entier, la fin de l'ann\u00e9e est marqu\u00e9e par la c\u00e9l\u00e9bration des f\u00eates de fin d'ann\u00e9e. Que vous c\u00e9l\u00e9briez Hanoukka, No\u00ebl, Yule, Boxing Day, Kwanzaa, le Solstice d'hiver ou toute autre f\u00eate de cette p\u00e9riode de l'ann\u00e9e, je tiens \u00e0 vous souhaiter...<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"275\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-1024x275.png\" alt=\"\" class=\"wp-image-3363\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-1024x275.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-600x161.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-300x81.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-768x206.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-18x5.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays-570x153.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Happy-Holidays.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\"><span style=\"color:#088483\" class=\"has-inline-color\"><em>\u201cHeureuse la saison qui engage le monde entier dans une conspiration d'amour.\u201d<\/em><br>~ Hamilton Wright Mabie<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-rotated.jpg\" alt=\"\" class=\"wp-image-3365\" width=\"568\" height=\"426\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-rotated.jpg 939w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-rotated-600x450.jpg 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-300x225.jpg 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-768x576.jpg 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-16x12.jpg 16w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Droplet-1-570x427.jpg 570w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/figure><\/div>\n\n\n\n<p>Je suis reconnaissante \u00e0 cette communaut\u00e9 de lecteurs et de sympathisants, et je suis reconnaissante de pouvoir participer \u00e0 une \u201cconspiration de l'amour\u201d annuelle. J'esp\u00e8re que vous vous joindrez \u00e0 moi pour conspirer en cette p\u00e9riode de f\u00eates de fin d'ann\u00e9e !<br><br>J'ai h\u00e2te de vous retrouver de l'autre c\u00f4t\u00e9 des f\u00eates, pr\u00eate pour une nouvelle ann\u00e9e de soutien mutuel et d'inspiration par le biais de ce blog. Notre article de janvier traitera de la d\u00e9finition des intentions et de la r\u00e9alisation des objectifs avec succ\u00e8s. Restez \u00e0 l'\u00e9coute !<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-1024x640.png\" alt=\"\" class=\"wp-image-3360\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-1024x640.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-600x375.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-300x188.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-768x480.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-18x12.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast-570x356.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Champagne-toast.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>I don\u2019t know about you but it\u2019s been another rough year\u2026 Between Covid in the forefront and climate change in the background, no matter where you are in the world, no one can escape the hardships the present times pose. There are thankfully many tools [&#8230;]<\/p>\n","protected":false},"author":14,"featured_media":3359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-3358","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-uncategorized","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2021 - The Year in Review &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/fr\/year-in-review\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2021 - The Year in Review &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"I don\u2019t know about you but it\u2019s been another rough year\u2026 Between Covid in the forefront and climate change in the background, no matter where you are in the world, no one can escape the hardships the present times pose. There are thankfully many tools [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/fr\/year-in-review\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T18:20:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-13T13:44:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pascale Brady\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascale Brady\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review\"},\"author\":{\"name\":\"Pascale Brady\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\"},\"headline\":\"2021 &#8211; The Year in Review\",\"datePublished\":\"2021-12-14T18:20:31+00:00\",\"dateModified\":\"2022-01-13T13:44:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review\"},\"wordCount\":692,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Snowman-Copy.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review\",\"name\":\"2021 - The Year in Review &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Snowman-Copy.png\",\"datePublished\":\"2021-12-14T18:20:31+00:00\",\"dateModified\":\"2022-01-13T13:44:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Snowman-Copy.png\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Snowman-Copy.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/year-in-review#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021 &#8211; The Year in Review\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\",\"name\":\"Pascale Brady\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"caption\":\"Pascale Brady\"},\"sameAs\":[\"https:\\\/\\\/thechallengecoach.com\\\/meet-pascale\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021 - The Year in Review &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/fr\/year-in-review\/","og_locale":"fr_FR","og_type":"article","og_title":"2021 - The Year in Review &#8211; The Challenge Coach","og_description":"I don\u2019t know about you but it\u2019s been another rough year\u2026 Between Covid in the forefront and climate change in the background, no matter where you are in the world, no one can escape the hardships the present times pose. There are thankfully many tools [...]","og_url":"https:\/\/thechallengecoach.com\/fr\/year-in-review\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","article_published_time":"2021-12-14T18:20:31+00:00","article_modified_time":"2022-01-13T13:44:07+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","type":"image\/png"}],"author":"Pascale Brady","twitter_card":"summary_large_image","twitter_creator":"@pascalebrady","twitter_site":"@pascalebrady","twitter_misc":{"\u00c9crit par":"Pascale Brady","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thechallengecoach.com\/year-in-review#article","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/year-in-review"},"author":{"name":"Pascale Brady","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0"},"headline":"2021 &#8211; The Year in Review","datePublished":"2021-12-14T18:20:31+00:00","dateModified":"2022-01-13T13:44:07+00:00","mainEntityOfPage":{"@id":"https:\/\/thechallengecoach.com\/year-in-review"},"wordCount":692,"commentCount":0,"publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"image":{"@id":"https:\/\/thechallengecoach.com\/year-in-review#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thechallengecoach.com\/year-in-review#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/year-in-review","url":"https:\/\/thechallengecoach.com\/year-in-review","name":"2021 - The Year in Review &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/year-in-review#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/year-in-review#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","datePublished":"2021-12-14T18:20:31+00:00","dateModified":"2022-01-13T13:44:07+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/year-in-review#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/year-in-review"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/year-in-review#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/year-in-review#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"2021 &#8211; The Year in Review"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"La coach du d\u00e9fi","description":"Transformer les d\u00e9fis en croissance et succ\u00e8s","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"La coach du d\u00e9fi","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]},{"@type":"Person","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0","name":"Pascale Brady","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","caption":"Pascale Brady"},"sameAs":["https:\/\/thechallengecoach.com\/meet-pascale"]}]}},"jetpack_featured_media_url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/12\/Snowman-Copy.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/posts\/3358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/comments?post=3358"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/posts\/3358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media\/3359"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/media?parent=3358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/categories?post=3358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/fr\/wp-json\/wp\/v2\/tags?post=3358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}