{"id":10000582,"date":"2026-03-24T14:39:40","date_gmt":"2026-03-24T19:39:40","guid":{"rendered":"https:\/\/thechallengecoach.com\/?post_type=tribe_events&#038;p=5590"},"modified":"2026-03-24T14:39:40","modified_gmt":"2026-03-24T19:39:40","slug":"cours-de-parentalite-positive-2","status":"publish","type":"tribe_events","link":"https:\/\/thechallengecoach.com\/de\/event\/cours-de-parentalite-positive-2\/2026-04-22","title":{"rendered":"KURS DER ELTERNSCHAFT POSITIV"},"content":{"rendered":"<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<div>Haben Sie so viel Zeit, um die gleichen Anforderungen zu erf\u00fcllen? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez ? Und schlie\u00dflich m\u00fcssen Sie regelm\u00e4\u00dfig den Anspr\u00fcchen Ihrer Kinder gerecht werden, um die Kinder zu ern\u00e4hren oder, noch schlimmer, um die Pillen zu schlucken...<br \/>\n<br aria-hidden=\"true\" \/>Lernen Sie, was positive Elternschaft ist, ein auf der Psychologie von Alfred Adler basierendes Erziehungssystem, das zu einer besseren Kommunikation und Zusammenarbeit zwischen Eltern und Kindern f\u00fchrt und gleichzeitig Grenzen und geteilte Verantwortung f\u00f6rdert.<br \/>\n<br aria-hidden=\"true\" \/>Sie werden mit konkreten, sofort anwendbaren Hilfsmitteln ausgestattet, die zu einem famili\u00e4ren Umfeld f\u00fchren, das nicht nur angenehmer, sondern auch harmonischer ist.<br \/>\n<br aria-hidden=\"true\" \/>Dieser Kurs ist partizipativ, interaktiv und kann das Leben radikal ver\u00e4ndern.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong data-stringify-type=\"bold\">POURQUOI ?<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">Eines der Dinge, die man in der Schule nicht lernt, ist, Eltern zu sein. Das ist schade, denn es ist einer der schwierigsten Berufe der Welt und einer der folgenreichsten und folgenreichsten. Unsere Erziehungsentscheidungen beruhen daher entweder auf unseren Erfahrungen als Kinder (man tut, was man als Eltern getan hat, oder umgekehrt!), oder\/und man informiert sich \u00fcber die M\u00f6glichkeiten, die man hat, um seinen eigenen Weg zu finden. In allen F\u00e4llen t\u00e2tonne on pas mal und on s'en sort du mieux qu'on peut. \u00c7a ne serait pas mieux avec un bon mode d'emploi ?<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlock\">\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/e8e76759-883a-74bf-08b7-e5ea1b19b958.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>POUR QUI ?<\/strong><\/h3>\n<h4>Jeder erwachsene Frankophone (*), der mit Kindern im Alter von 2 bis 18 Jahren zu tun hat (Eltern, zuk\u00fcnftige Eltern, Gro\u00dfeltern, Kinderm\u00e4dchen oder -v\u00e4ter, Schulleiter, G\u00e4rtner usw.).<br aria-hidden=\"true\" \/>(*) Les cours seront en langue fran\u00e7aise<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/39cda3aa-a06f-b442-5873-28a3648a2a02.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>QUAND ?<\/strong><\/h3>\n<h4>Les mercredis soirs \u00e0 20h EST (Kurs von 75 Minuten - heure de New York)<br aria-hidden=\"true\" \/>Du mercredi 25 mars 2026 au 13 mai 2026<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnCaptionBlockInner\">\n<div class=\"\">\n<div>\n<div class=\"mcnCaptionBottomImageContent\"><img decoding=\"async\" class=\"mcnImage tc-smart-loaded\" src=\"https:\/\/mcusercontent.com\/e2a090dacf09a83346da8dac7\/images\/0faf7744-0839-e4f5-4574-0225c95bdb52.jpeg\" alt=\"\" width=\"1000\" \/><\/div>\n<\/div>\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>O\u00d9 ?<\/strong><\/h3>\n<h4>Sur zoom! Die Kurse werden in dem Fall registriert, in dem Sie verpflichtet sind, einen Kurs zu belegen (die pers\u00f6nliche Teilnahme wird jedoch dringend empfohlen).<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>CONTENU<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnBoxedTextBlock\">\n<div class=\"mcnBoxedTextBlockInner\">\n<div class=\"mcnBoxedTextBlockColumn\">\n<div class=\"mcnTextContentContainer mcnTextContent\">\n<div><strong>Sitzung 1<\/strong><br \/>\nEinf\u00fchrungen und Ziele - Erziehungsstile<\/div>\n<div><strong>Sitzung 2<\/strong><br \/>\nDie Entwicklung der Pers\u00f6nlichkeit<\/div>\n<div><strong>Sitzung 3<\/strong><br \/>\nEntmutigung\/Ermutigung<\/div>\n<div><strong>Sitzung 4<\/strong><br \/>\nGrenzen und Folgen<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnBoxedTextBlockColumn\">\n<div class=\"mcnTextContentContainer mcnTextContent\">\n<div><strong>Sitzung 5<\/strong><br \/>\nDie Verhaltensweisen von Kindern kennenlernen<br \/>\n<br aria-hidden=\"true\" \/><strong>Sitzung 6<\/strong><br \/>\nVerhaltensweisen korrigieren - Ausbildung<br \/>\n<br aria-hidden=\"true\" \/><strong>Sitzung 7<\/strong><br \/>\nKommunikation - Ecoute<\/div>\n<div><strong>Sitzung 8<\/strong><br \/>\nZeitschrift: compilation et Conseil de famille<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>CO\u00dbT<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div class=\"mcnTextContent\">F\u00fcr diese 8 Sitzungen von 75 Minuten (insgesamt 10 Stunden Inhalt):<br aria-hidden=\"true\" \/>$199 (soit $20\/heure)<\/p>\n<p><b><i>WICHTIG! <\/i><\/b><i>Unsere Absicht und unser Wunsch ist es, dieses Programm f\u00fcr eine gro\u00dfe Anzahl von Menschen anzubieten. Si vous \u00eates int\u00e9r\u00e9ss\u00e9(e) et souhaitez nous rejoindre mais que ce co\u00fbt est prohibitif pour vous - pour quelque raison que ce soit - des tarifs r\u00e9duits sont offerts. Bitte nehmen Sie direkt mit Pascale Kontakt auf, um sich zu beraten.<\/i><\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h3 class=\"null\"><strong>PAR QUI ?<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">Dieser Kurs wird Ihnen von Pascale Brady angeboten, <a href=\"https:\/\/thechallengecoach.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/thechallengecoach.com\/\">Der Challenge Coach<\/a>. Pascale ist ein zertifizierter Lebens- und Wirtschaftscoach (CPPC, PCC) und auch eine zertifizierte Erzieherin f\u00fcr Kindererziehung nach PEP (le\u00a0<a href=\"https:\/\/pepparent.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/pepparent.org\/\">Programm zur F\u00f6rderung der Eltern<\/a>) und\u00a0<a href=\"https:\/\/positivediscipline.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-sk=\"tooltip_parent\" data-stringify-link=\"https:\/\/positivediscipline.org\/\">Positive Disziplin<\/a>\u00a0mit mehr als 20 Jahren Erfahrung im Bereich Coaching und Elternschaft.<\/div>\n<\/div>\n<div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<h4 class=\"null\"><strong>Eine kleine Einf\u00fchrung zu den Kursen und praktischen Informationen<\/strong><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mcnButtonBlock mcnButtonBlockInner\">\n<div><a id=\"0\" class=\"mcnButtonContentContainer mcnButton\" title=\"Eine kleine Einf\u00fchrung ICI\" href=\"https:\/\/us02web.zoom.us\/rec\/play\/MQUPPEpcKookJ1GlP74Ku2yI_iT5zNPkFOik3flUw5uGazi4OCyhp1m1C5_WdocjK_R6lInWeYRuyfow.jBTiKG_qW6eDWfMP?eagerLoadZvaPages=sidemenu.billing.plan_management&amp;accessLevel=meeting&amp;canPlayFromShare=true&amp;from=my_recording&amp;startTime=1759783586000&amp;componentName=rec-play&amp;originRequestUrl=https%3A%2F%2Fus02web.zoom.us%2Frec%2Fshare%2FdcaddhxdGxAjI0AyfNKNDsdDEPPvyqvP2kFippzZwBke34MnVdkWtWcCg2aho6K4.Pko04RaDRpASBOjm%3FstartTime%3D1759783586000%26fbclid%3DIwY2xjawNZwg5leHRuA2FlbQIxMABicmlkETFVRm50M05ManpPTlVKcXpVAR5WAXXVCd7J5-Qi-vi6O956erYGk_MEfCwT3JrBp2QFW04s-AVQ5uMHyYzasg_aem_cQfkXygNqccNZ3tPXfEXMQ\" target=\"_blank\" rel=\"noopener\">Eine kleine Einf\u00fchrung ICI<\/a><\/div>\n<\/div>\n<div class=\"mcnTextBlock\">\n<div class=\"mcnTextBlockInner\">\n<div>\n<div class=\"mcnTextContent\">\n<div><strong>Passcode: %g46aMUE<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5050,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":{"0":"post-10000582","1":"tribe_events","2":"type-tribe_events","3":"status-publish","4":"has-post-thumbnail","6":"tribe-recurring-event","7":"tribe-recurring-event-parent","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/de\/event\/cours-de-parentalite-positive-2\/2026-04-22\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/de\/event\/cours-de-parentalite-positive-2\/2026-04-22\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22\",\"name\":\"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"datePublished\":\"2026-03-24T19:39:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AdobeStock_1394973649-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"In a moment of joy, a young girl gives a thumbs-up in response to encouragement, highlighting positive reinforcement during her learning process.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/event\\\/cours-de-parentalite-positive-2\\\/2026-04-22#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COURS DE PARENTALIT\u00c9 POSITIVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/de\/event\/cours-de-parentalite-positive-2\/2026-04-22\/","og_locale":"de_DE","og_type":"article","og_title":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","og_description":"Vous en avez assez de r\u00e9p\u00e9ter sans cesse les m\u00eames demandes? De vous battre du matin au soir pour que vos enfants vous \u00e9coutent et fassent ce que vous demandez [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/de\/event\/cours-de-parentalite-positive-2\/2026-04-22\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","og_image":[{"width":2560,"height":1707,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@pascalebrady","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22","url":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22","name":"COURS DE PARENTALIT\u00c9 POSITIVE &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","datePublished":"2026-03-24T19:39:40+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2025\/10\/AdobeStock_1394973649-scaled.jpeg","width":2560,"height":1707,"caption":"In a moment of joy, a young girl gives a thumbs-up in response to encouragement, highlighting positive reinforcement during her learning process."},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/event\/cours-de-parentalite-positive-2\/2026-04-22#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/thechallengecoach.com\/events\/"},{"@type":"ListItem","position":3,"name":"COURS DE PARENTALIT\u00c9 POSITIVE"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"Der Challenge Coach","description":"Herausforderungen in Wachstum und Erfolg verwandeln","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"Der Challenge Coach","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tribe_events\/10000582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tribe_events\/10000582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media\/5050"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media?parent=10000582"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tags?post=10000582"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10000582"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}