{"id":4315,"date":"2024-05-23T09:18:35","date_gmt":"2024-05-23T14:18:35","guid":{"rendered":"https:\/\/thechallengecoach.com\/?p=4315"},"modified":"2024-09-26T05:03:29","modified_gmt":"2024-09-26T10:03:29","slug":"know-thyself","status":"publish","type":"post","link":"https:\/\/thechallengecoach.com\/de\/know-thyself","title":{"rendered":"Erkenne dich selbst"},"content":{"rendered":"<p>Inzwischen wissen einige von Ihnen, dass ich ein Coach bin \ud83d\ude09 - vor allem ein Life Coach. Wie wir in unserem letzten Newsletter besprochen haben, kommen Menschen zum Coaching, weil der aktuelle Zustand, in dem sie sich befinden, nicht der ideale Zustand ist, in dem sie gerne sein w\u00fcrden. Coaching-Klienten stecken oft irgendwo fest: in einer schlechten gesundheitlichen Situation, in einem labilen emotionalen Zustand, in einer dysfunktionalen Beziehung, in einem schrecklichen Job oder auf dem falschen Karriereweg ... Und wie so viele von uns denken sie, \u201cwenn sich nur etwas \u00e4ndern w\u00fcrde, w\u00fcrde alles viel besser werden\u201d. Was sie normalerweise mit \u201cetwas\u201d meinen, ist:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sie selbst: \u201cWenn ich doch nur mehr Willenskraft h\u00e4tte und aufh\u00f6ren k\u00f6nnte, all das Junkfood zu essen\u201d, oder \u201cWenn ich doch nur lernen k\u00f6nnte, mich nicht mehr um Kleinigkeiten zu k\u00fcmmern\u201d, oder \u201cWenn ich doch nur weniger sch\u00fcchtern sein und mehr Selbstvertrauen haben k\u00f6nnte\u201d.<\/li>\n\n\n\n<li>Andere: \u201cWenn er doch nur aufh\u00f6ren k\u00f6nnte, sich so sehr mit dem Golfsport zu besch\u00e4ftigen und sich mehr auf mich konzentrieren w\u00fcrde\u201d, oder \u201cSie kritisiert mich st\u00e4ndig und interessiert sich \u00fcberhaupt nicht f\u00fcr meine Sicht der Dinge\u201d.<\/li>\n\n\n\n<li>Die Umst\u00e4nde: \u201cIch muss nur noch dieses gro\u00dfe Projekt zu Ende bringen. Dann kann ich eine Pause einlegen\u201d, oder \u201cSobald Covid vorbei ist, k\u00f6nnen wir unser normales Leben wieder aufnehmen\u201d.<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;<br>Mit anderen Worten: Wir wollen, dass die Dinge anders sind, als sie sind. Und ich sage \u201cwir\u201d, weil ich nicht nur \u00fcber die Kunden spreche, die ich betreue: Ich spreche von so gut wie jedem von uns! Coaching-Kunden sind an einem Punkt angelangt, an dem sie mit dem Status quo fertig sind und etwas \u00e4ndern wollen.<br>&nbsp;<br>So viele von uns wollen, dass wir anders sind, oder dass sich andere oder die Umst\u00e4nde um uns herum \u00e4ndern. Wir wollen nicht akzeptieren, was ist, wie es ist. Das Problem mit dieser Haltung ist, dass es keinen Ruhepunkt gibt, wenn man sich dem widersetzt, was ist. Auch gibt es im Widerstand keine produktive Bewegung in Richtung Ver\u00e4nderung. Paradoxerweise gilt: Je mehr wir uns daran klammern, etwas anderes zu wollen als das, was wir sind oder bereits haben, desto mehr bleiben wir in dem stecken, was ist, und desto weniger bewegen wir uns auf den besseren Ort des Seins oder Handelns zu, den wir suchen. Es ist ein bisschen so, als w\u00fcrden wir im Treibsand stecken bleiben.<\/p>\n\n\n\n<p>Lassen Sie uns also heute eine Reise ins Innere machen, ja?<\/p>\n\n\n\n<p><strong>WIE GUT KENNST DU DICH SELBST?<\/strong><\/p>\n\n\n\n<p><br>Sich selbst zu verstehen ist wie die Feinabstimmung eines Instruments. Indem wir in die Tiefen unseres Wesens eintauchen, gewinnen wir Einblicke in unseren Kern, sowohl in unser k\u00f6rperliches als auch in unser geistiges\/emotionales Selbst.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"370\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-1024x370.png\" alt=\"\" class=\"wp-image-4326\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-1024x370.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-300x109.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-768x278.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-570x206.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1-600x217.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/1-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>1. UNSERE NATUR\/TEMPERAMENT (GEISTIGES\/EMOTIONALES SELBST)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-1024x536.png\" alt=\"\" class=\"wp-image-4327\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/2-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Schauen wir uns zun\u00e4chst das Temperament an. Beantworten Sie die folgenden Fragen. Versuchen Sie dabei, sie so zu beantworten, wie Sie es vielleicht getan h\u00e4tten, als Sie noch ein kleines Kind waren, z. B. vor dem sechsten Lebensjahr, denn damals waren Sie noch Ihr authentischstes Selbst, noch nicht durch die Erziehung, die Sie erfahren haben, die Kultur, in der Sie aufgewachsen sind, und Ihre Lebensumst\u00e4nde in andere Formen gebogen.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aktivit\u00e4tsniveau: Sind Sie ein ruhiger Mensch oder eher aktiv? Wie ist Ihr Wohlf\u00fchlverh\u00e4ltnis zwischen Inaktivit\u00e4t und Aktivit\u00e4t?<\/li>\n\n\n\n<li>Biorhythmik\/Regelm\u00e4\u00dfigkeit: Wie regelm\u00e4\u00dfig sind Sie k\u00f6rperlich? Tun Sie Dinge immer zur gleichen Tageszeit oder sind Sie angenehm unberechenbar in Ihrem Biorhythmus?<\/li>\n\n\n\n<li>Ann\u00e4herung\/Zur\u00fcckziehen: Gehen Sie leicht und nat\u00fcrlich auf Menschen, Dinge oder neue Situationen zu, oder neigen Sie dazu, zuerst zur\u00fcckzuschrecken und brauchen Zeit, um warm zu werden?<\/li>\n\n\n\n<li>Anpassungsf\u00e4higkeit: F\u00fchlen Sie sich wohl oder sind Sie verunsichert, wenn sich etwas \u00e4ndert?<\/li>\n\n\n\n<li>Sensorische Schwelle: Wie hoch ist Ihre sensorische Schwelle? Mit anderen Worten: Wie empfindlich sind Sie gegen\u00fcber \u00e4u\u00dferen Reizen?<\/li>\n\n\n\n<li>Stimmung: Wie ist Ihre Grundqualit\u00e4t der Stimmung? Sind Sie eher \u201cdas Glas halb leer\u201d oder \u201cdas Glas halb voll\u201d?<\/li>\n\n\n\n<li>Intensit\u00e4t der Reaktionen: Wie intensiv sind Ihre emotionalen Reaktionen (ob positiv oder negativ)? Haben Sie eher einen niedrigen oder einen \u00fcberschw\u00e4nglichen emotionalen Affekt?<\/li>\n\n\n\n<li>Ablenkbarkeit: Wie hoch ist Ihr Grad der Ablenkbarkeit? Sind Sie jemand, dem es leicht f\u00e4llt, sich zu konzentrieren, oder lassen Sie sich leicht ablenken?<\/li>\n\n\n\n<li>Ausdauer\/Aufmerksamkeitsspanne: Wie hoch ist Ihr Durchhalteverm\u00f6gen? K\u00f6nnen Sie bei einer schwierigen Aufgabe lange durchhalten oder geben Sie leicht auf?<\/li>\n<\/ol>\n\n\n\n<p>Dies sind die neun Temperamentseigenschaften, die die Forscher Stella Chess von der NYU und ihr Mann Alexander Thomas in ihrer New Yorker L\u00e4ngsschnittstudie von 1950 bis 1968 herausgefunden haben. Die Studie kam zu dem Schluss, dass unsere Temperamente bereits vor unserer Geburt festgelegt werden, und f\u00fchrte zur \u201cGoodness of Fit\u201d-Theorie, die sich auf die \u00dcbereinstimmung zwischen dem individuellen Temperament des Kindes und den Anforderungen und Erwartungen der Umwelt bezieht.<br><br>Hinweis: Es gibt keine GUTEN oder SCHLECHTEN Antworten auf den obigen Fragebogen zum Temperament. Es gibt nur das, was ist. Wer Sie in Ihrem nat\u00fcrlichen Zustand sind. Probleme treten erst dann auf, wenn wir uns durch das, was Chess und Thomas als \u201cdie Anforderungen und Erwartungen der Umwelt\u201d bezeichneten, aus unserer nat\u00fcrlichen Form herausbiegen oder uns verbiegen lassen. Wenn Sie sich Ihres Temperaments voll bewusst sind und sich daf\u00fcr entscheiden, es in den Grenzen des gesellschaftlichen Lebens so weit wie m\u00f6glich zu respektieren, werden Sie sich nicht aus Ihrer nat\u00fcrlichen Temperamentsform herausgebeugt f\u00fchlen und mehr in Harmonie mit sich selbst sein. Im wahrsten Sinne des Wortes werden Sie sich mehr wie Sie selbst f\u00fchlen, also entspannter und weniger gestresst sein, als wenn Sie versuchen, jemand zu sein, der Sie nicht sind.<br><br>Ist das immer m\u00f6glich? Nein, nat\u00fcrlich nicht. Wir sind soziale Wesen und leben mit anderen in einer Gesellschaft. Wenn Sie auf der Skala \u201cIntensit\u00e4t\u201d einen sehr hohen Wert haben, k\u00f6nnten Sie sich erlauben, bei allem, was Ihnen in die Quere kommt, in die Luft zu gehen und au\u00dfer Kontrolle zu geraten, was offensichtlich ein inakzeptables soziales Verhalten ist. Was ist also los? Es ist eine Frage der \u201cFeinabstimmung\u201d, wie wir oben sagten. Es geht darum, sich selbst zu kennen, einschlie\u00dflich dessen, was unter bestimmten Umst\u00e4nden passt und was nicht, und sich entsprechend anzupassen. Die Botschaft lautet jedoch, dass wir versuchen sollten, unser Leben so zu gestalten, dass wir die meiste Zeit in unserem nat\u00fcrlichen Zustand sein k\u00f6nnen. Mit anderen Worten, wir sollten versuchen, Menschen, Orte und Berufe zu w\u00e4hlen, die gut zu uns passen, damit wir so oft wie m\u00f6glich unser bestes Selbst sein k\u00f6nnen. Das ist wichtig, denn \u201cwir TUN gut, wenn wir uns gut f\u00fchlen\u201d.\u201d<\/p>\n\n\n\n<p><strong>2. UNSER PHYSISCHES SELBST<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-1024x536.png\" alt=\"\" class=\"wp-image-4318\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/3.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Zweitens, lassen Sie uns in Ihren physischen K\u00f6rper eintauchen. (Erinnert sich jemand an die <a href=\"https:\/\/www.youtube.com\/watch?v=mMOVRp3NSoY\">Der Zauberschulbus<\/a>\u2019Reisen im K\u00f6rper?). Wie sehr sind Sie auf das eingestimmt, was innerhalb Ihrer physischen H\u00fclle vor sich geht?<br>&nbsp;<br>Stellen Sie sich diesen Tag vor: Sie haben extrem schlecht geschlafen und wachen m\u00fcde und m\u00fcrrisch auf, ohne wirklich zu wissen, warum, oder es sogar bewusst wahrzunehmen. Ihre Kinder streiten sich beim Fr\u00fchst\u00fcck und die Milchflasche landet auf dem Boden. Du knirschst mit den Z\u00e4hnen und versuchst, ruhig zu bleiben, aber schlie\u00dflich verlierst du die Beherrschung und schreist, so dass schlie\u00dflich alle aus der T\u00fcr gehen. Jetzt kommen Sie alle zu sp\u00e4t zur Schule und zur Arbeit - die Kinder verpassen den Schulbus und auf dem Weg ins B\u00fcro stehen Sie im Stau. Du kommst mit starken Kopfschmerzen an und w\u00fcnschst dir, du k\u00f6nntest nach Hause gehen ... Aber du hast keine Wahl - du musst hingehen. Ihr Arbeitstag ist anstrengend: Ihre Kunden sind sehr ver\u00e4rgert \u00fcber die versp\u00e4tete Lieferung ihrer Bestellung, und Ihr Chef ist unglaublich w\u00fctend auf Sie, weil Sie das zugelassen haben. Mitten in diesem verr\u00fcckten Tag voller Besprechungen, in denen dich alle anzuschreien scheinen, schickt dir deine Mutter eine SMS, um dir mitzuteilen, dass dein Vater die Treppe hinuntergefallen ist und gerade ins Krankenhaus gebracht wurde. Du st\u00e4hlst dich, bis du endlich die Arbeit verlassen kannst (sp\u00e4ter als sonst), um ins Krankenhaus zu fahren, wo du deine Mutter tr\u00f6stest, w\u00e4hrend dein Vater operiert wird. Dann m\u00fcssen Sie nach Hause eilen, um den Babysitter abzul\u00f6sen (Ihr Ehepartner ist auf Gesch\u00e4ftsreise). Die Kinder haben den Streit, den sie am Morgen begonnen haben, nahtlos fortgesetzt, und niemand hat mit den Hausaufgaben angefangen, geschweige denn mit dem Abendessen. Schlie\u00dflich rasten Sie aus, schreien die Kinder an und schicken sie ohne ein \"Gute Nacht\" ins Bett. Sie lassen sich auf die Couch fallen und starren ins Leere, bis Sie sich endlich so weit erholt haben, dass Sie die Kraft haben, sich und Ihre massive Migr\u00e4ne ins Bett zu schleppen. Sie sind sich nicht sicher, wie Sie am Morgen aus dem Bett kommen sollen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-1024x536.png\" alt=\"\" class=\"wp-image-4319\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/4.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Was w\u00e4re anders gewesen, wenn Sie Ihren K\u00f6rper wirklich gut kennen w\u00fcrden, so dass Sie die bekannten Anzeichen von Stress erkennen k\u00f6nnten, sobald sie auftreten? Was w\u00e4re, wenn Sie achtsamer gewesen w\u00e4ren und Ihren Tag nicht nur \u201c\u00fcberstanden\u201d h\u00e4tten, sondern ihn stattdessen aktiv mitgestaltet h\u00e4tten, indem Sie sich selbst besser kennengelernt h\u00e4tten?<br>&nbsp;<br>Als Sie aufgewacht sind, haben Sie sich einen Moment Zeit genommen, um Bilanz \u00fcber Ihre Nacht zu ziehen. Vielleicht haben Sie festgestellt, dass Sie schlecht geschlafen haben, und sich einen zus\u00e4tzlichen Moment der Selbstf\u00fcrsorge geg\u00f6nnt, um die schlechte Nacht auszugleichen (mit einer sch\u00f6nen hei\u00dfen Dusche und einem ruhigen Moment allein mit Ihrer Lieblingstasse Tee und Ihrer Morgenmeditation). Als Sie in die K\u00fcche gehen, wo sich Ihre Kinder streiten, k\u00f6nnen Sie, da Sie sich gerade einen Moment Zeit f\u00fcr sich selbst genommen haben, den Streit zwischen den Kindern beruhigen und sie um ihre Unterst\u00fctzung beim Aufr\u00e4umen bitten, damit Sie alle rechtzeitig aus dem Haus gehen k\u00f6nnen. Keiner kommt zu sp\u00e4t zur Schule\/Arbeit. Der Verkehr auf dem Weg zur Arbeit gibt Ihnen Gelegenheit, sich auszuruhen und sich zu sammeln. Sie merken, dass Sie morgens wieder etwas angespannt sind, und atmen ein paar Mal tief durch, um sich zu entspannen. Sie konzentrieren sich auf die pr\u00e4chtig bl\u00fchenden B\u00e4ume entlang der Autobahn. Sie legen eine Musik auf, die Ihnen Freude bereitet. Sie kommen bei der Arbeit an und - trotz der Tatsache, dass die Probleme alle die gleichen sind - k\u00f6nnen Sie die verschiedenen Krisen viel besser bew\u00e4ltigen, weil Sie ruhig und gelassen hineingehen. Dank Ihres ruhigen Verhaltens und Ihrer F\u00e4higkeit, die Dinge nicht pers\u00f6nlich zu nehmen, werden die Probleme kreativ angegangen und L\u00f6sungen gefunden. Als Sie die SMS Ihrer Mutter \u00fcber den Unfall Ihres Vaters erhalten, k\u00f6nnen Sie diesem Notfall Priorit\u00e4t einr\u00e4umen und mit Kollegen und Ihrem Vorgesetzten aushandeln, dass Sie fr\u00fcher gehen, um sich um die Situation zu k\u00fcmmern. Auf dem Heimweg stellen Sie fest, dass Sie durch den Stress des Tages eine Migr\u00e4ne bekommen haben. Sie ergreifen sofort geeignete Ma\u00dfnahmen (Sonnenbrille, Migr\u00e4netabletten, Schlie\u00dfen der Fenster und Ausschalten des Radios), so dass Sie, wenn Sie zu Hause zur T\u00fcr hereinkommen, wissen, dass Sie alles in Ihrer Macht Stehende getan haben, um die Migr\u00e4ne einzud\u00e4mmen. Sie sagen allen, dass Sie ins Bett gehen m\u00fcssen. K\u00f6nnten sie sich bitte selbst f\u00fcttern und sich um den Hund k\u00fcmmern und leise gute Nacht sagen, wenn sie fertig sind?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-1024x536.png\" alt=\"\" class=\"wp-image-4320\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/5.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Derselbe Tag, dieselben Umst\u00e4nde, unterschiedliche Erfahrungen f\u00fcr Sie und andere. Indem Sie sich selbst kennen, Ihren Erfahrungen Aufmerksamkeit schenken und sich die Zeit nehmen, sich um Ihre k\u00f6rperlichen Erfahrungen zu k\u00fcmmern, w\u00e4hrend sie sich entfalten, passen Sie sich in Echtzeit an und kalibrieren sich neu. Dadurch sind Sie in der Lage, aus einer weniger reaktiven Haltung heraus zu handeln und jedes Problem, das sich Ihnen stellt, auf eine produktivere Weise zu l\u00f6sen. Infolgedessen k\u00f6nnen Sie Ihren Stresspegel niedrig halten, Ihr Wohlbefinden f\u00f6rdern und so insgesamt bessere Ergebnisse f\u00fcr diesen sehr schwierigen Tag erzielen. Sie haben auch weniger kumulative Stressauswirkungen auf Ihre allgemeine Gesundheit, da Sie den Stress in Echtzeit bew\u00e4ltigen. Wie Epictetus sagte: \u201cEs kommt nicht darauf an, was dir passiert, sondern wie du darauf reagierst.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"370\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-1024x370.png\" alt=\"\" class=\"wp-image-4321\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-1024x370.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-300x109.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-768x278.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-570x206.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6-600x217.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/6.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Dieses tiefe Wissen \u00fcber unser mentales, emotionales und k\u00f6rperliches Selbst dient als Kompass, der uns zum optimalen Funktionieren f\u00fchrt. Je mehr wir uns auf uns selbst einstellen, desto besser k\u00f6nnen wir unsere Handlungen, Gedanken und Emotionen auf unser wahres Wesen abstimmen und sowohl den Bed\u00fcrfnissen der Situation als auch dem Allgemeinwohl dienen.<\/p>\n\n\n\n<p><strong>3. UNSER KOH\u00c4RENTES\/AUTHENTISCHES SELBST<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-1024x536.png\" alt=\"\" class=\"wp-image-4322\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/7.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nachdem wir nun den Grundstein f\u00fcr unser Selbstverst\u00e4ndnis gelegt haben, wollen wir erkunden, wie wir durch die Annahme unseres authentischen Selbst einen sinnvollen Beitrag zur Welt leisten k\u00f6nnen.<br>&nbsp;<br>Die Positive Psychologie lehrt uns etwas \u00fcber authentische St\u00e4rken - die angeborenen Qualit\u00e4ten und Tugenden, die uns zu dem machen, was wir sind. Die Positive Psychologie entstand 1998 als neues Gebiet der Psychologie, als <a href=\"https:\/\/en.wikipedia.org\/wiki\/Martin_Seligman\">Martin Seligmann<\/a> w\u00e4hlte es als Thema f\u00fcr seine Amtszeit als Pr\u00e4sident der American Psychological Association. Seligman schl\u00e4gt vor, dass ein Mensch sein Wohlbefinden am besten f\u00f6rdern kann, indem er seine Charakterst\u00e4rken pflegt: Durch seine Forschung hat sein Team 24 universelle Charaktereigenschaften entdeckt, die wir alle in einer bestimmten und einzigartigen Reihenfolge besitzen. Mit dem VIA Strengths Survey Assessment k\u00f6nnen Sie herausfinden, in welcher Reihenfolge die 24 St\u00e4rken f\u00fcr Sie wichtig sind - und dabei besonders auf Ihre f\u00fcnf wichtigsten St\u00e4rken achten, die den Gro\u00dfteil Ihrer Charakterst\u00e4rken ausmachen. Seligman geht davon aus, dass man nur dann \u201cauthentisch gl\u00fccklich\u201d leben kann, wenn man seine f\u00fcnf wichtigsten St\u00e4rken beachtet. Umgekehrt kann es sein, dass man sich nicht ganz \u201crichtig\u201d oder vollkommen gl\u00fccklich f\u00fchlt, wenn man seine f\u00fcnf wichtigsten St\u00e4rken in seinem Leben nicht beachtet, weil man dann nicht authentisch ist. Kommt Ihnen das bekannt vor?<br>&nbsp;<br>Wenn wir von einem Ort der Authentizit\u00e4t aus agieren und unsere einzigartigen St\u00e4rken nutzen, geraten wir in einen Zustand des Flow. In diesem Zustand verschwindet die Zeit, und wir tauchen vollst\u00e4ndig in die anstehende Aufgabe ein und erleben ein tiefes Gef\u00fchl der Erf\u00fcllung. Indem wir unser authentisches Selbst annehmen und von einem Ort der \u00dcbereinstimmung aus agieren, werden wir zu Tr\u00e4gern eines positiven Wandels in der Welt. Wenn wir unsere Gaben und Talente authentisch einbringen, tragen wir zum kollektiven Gobelin der Menschheit bei und weben F\u00e4den des Mitgef\u00fchls, der Kreativit\u00e4t und der Freude.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"370\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-1024x370.png\" alt=\"\" class=\"wp-image-4323\" style=\"width:639px;height:auto\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-1024x370.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-300x109.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-768x278.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-570x206.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8-600x217.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/8.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Liebe Freunde, denkt daran, dass die Reise der Selbstentdeckung kein Ziel ist, sondern eine lebenslange Odyssee. M\u00f6get ihr auf dieser Reise Trost in den Tiefen eures Wesens und Mut in der Einzigartigkeit eures Wesens finden. Nehmt euch selbst an, ehrt eure St\u00e4rken und lasst euer Licht hell leuchten, um den Weg f\u00fcr andere zu erhellen.<\/p>\n\n\n\n<p>Mit Liebe und Licht,<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"127\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/12\/Signiture.png\" alt=\"\" class=\"wp-image-4246\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/12\/Signiture.png 249w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/12\/Signiture-18x9.png 18w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">ENTDECKEN SIE IHR AUTHENTISCHES SELBST - SONDERANGEBOT!<\/h2>\n\n\n\n<p>Entdecken Sie Ihr wahres Potenzial mit unserem exklusiven Angebot! Machen Sie den VIA Character Strengths Survey und buchen Sie eine pers\u00f6nliche Nachbesprechung mit mir f\u00fcr nur $199!<\/p>\n\n\n\n<p>Und so funktioniert es:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Buchen Sie Ihre Debriefing-Sitzung: Sichern Sie sich Ihren Platz zum Sonderpreis.<\/li>\n\n\n\n<li>Machen Sie die Umfrage: Nach der Buchung erhalten Sie detaillierte Anweisungen f\u00fcr die VIA-Charakterst\u00e4rken-Umfrage.<\/li>\n\n\n\n<li>Personalisierte Nachbesprechung: Gewinnen Sie Einblicke in Ihre charakterlichen St\u00e4rken und wie Sie diese f\u00fcr Ihr pers\u00f6nliches und berufliches Wachstum nutzen k\u00f6nnen.<\/li>\n<\/ol>\n\n\n\n<p>Verpassen Sie nicht diese Gelegenheit, Ihr authentisches Selbst zu entdecken. Buchen Sie jetzt und beginnen Sie Ihre Reise zur Selbstentdeckung!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/thechallengecoach.as.me\/?appointmentType=61853957\">60-MIN\u00dcTIGE COACHING-SITZUNG BUCHEN<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">ABONNIEREN SIE DEN NEWSLETTER DES CHALLENGE COACH<\/h3>\n\n\n\n<p>Sind Sie bereit, exklusive Einblicke, Tipps und Strategien zu erhalten, die Ihnen helfen, Ihre Herausforderungen zu meistern und Ihre Ziele zu erreichen? Dann besuchen Sie&nbsp;<a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/subscribe?u=e2a090dacf09a83346da8dac7&amp;id=c3689ce01e\">Melden Sie sich noch heute f\u00fcr den Newsletter von The Challenge Coach an<\/a>!<\/p>\n\n\n\n<p>Als Abonnent erhalten Sie Zugang zu:<\/p>\n\n\n\n<p>- Praktische Tipps und Ratschl\u00e4ge von The Challenge Coach<\/p>\n\n\n\n<p>- Inspirierende Geschichten<\/p>\n\n\n\n<p>- Rabatte f\u00fcr Coaching-Programme und Produkte<\/p>\n\n\n\n<p>... und vieles mehr!<\/p>\n\n\n\n<p>Verpassen Sie nicht diese unglaubliche Gelegenheit, mit dem Challenge Coach in Verbindung zu bleiben und Ihr pers\u00f6nliches Wachstum auf die n\u00e4chste Stufe zu heben.&nbsp;<a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/subscribe?u=e2a090dacf09a83346da8dac7&amp;id=c3689ce01e\">Jetzt anmelden<\/a>&nbsp;und werden Sie Teil unserer Gemeinschaft von engagierten, entschlossenen und bef\u00e4higten Menschen.<\/p>","protected":false},"excerpt":{"rendered":"<p>By now a few of you know that I am a coach \ud83d\ude09\u2013 mostly a life coach. As we discussed in our last newsletter, people come to coaching because the [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-4315","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-uncategorized","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Know Thyself &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/de\/know-thyself\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Know Thyself &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"By now a few of you know that I am a coach \ud83d\ude09\u2013 mostly a life coach. As we discussed in our last newsletter, people come to coaching because the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/de\/know-thyself\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T14:18:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T10:03:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pascale Brady\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascale Brady\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself\"},\"author\":{\"name\":\"Pascale Brady\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\"},\"headline\":\"Know Thyself\",\"datePublished\":\"2024-05-23T14:18:35+00:00\",\"dateModified\":\"2024-09-26T10:03:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself\"},\"wordCount\":2524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hEADER-Copy.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself\",\"name\":\"Know Thyself &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hEADER-Copy.png\",\"datePublished\":\"2024-05-23T14:18:35+00:00\",\"dateModified\":\"2024-09-26T10:03:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hEADER-Copy.png\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hEADER-Copy.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/know-thyself#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Know Thyself\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\",\"name\":\"Pascale Brady\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"caption\":\"Pascale Brady\"},\"sameAs\":[\"https:\\\/\\\/thechallengecoach.com\\\/meet-pascale\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Know Thyself &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/de\/know-thyself\/","og_locale":"de_DE","og_type":"article","og_title":"Know Thyself &#8211; The Challenge Coach","og_description":"By now a few of you know that I am a coach \ud83d\ude09\u2013 mostly a life coach. As we discussed in our last newsletter, people come to coaching because the [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/de\/know-thyself\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","article_published_time":"2024-05-23T14:18:35+00:00","article_modified_time":"2024-09-26T10:03:29+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","type":"image\/png"}],"author":"Pascale Brady","twitter_card":"summary_large_image","twitter_creator":"@pascalebrady","twitter_site":"@pascalebrady","twitter_misc":{"Verfasst von":"Pascale Brady","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thechallengecoach.com\/know-thyself#article","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/know-thyself"},"author":{"name":"Pascale Brady","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0"},"headline":"Know Thyself","datePublished":"2024-05-23T14:18:35+00:00","dateModified":"2024-09-26T10:03:29+00:00","mainEntityOfPage":{"@id":"https:\/\/thechallengecoach.com\/know-thyself"},"wordCount":2524,"commentCount":0,"publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"image":{"@id":"https:\/\/thechallengecoach.com\/know-thyself#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thechallengecoach.com\/know-thyself#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/know-thyself","url":"https:\/\/thechallengecoach.com\/know-thyself","name":"Know Thyself &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/know-thyself#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/know-thyself#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","datePublished":"2024-05-23T14:18:35+00:00","dateModified":"2024-09-26T10:03:29+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/know-thyself#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/know-thyself"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/know-thyself#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/know-thyself#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Know Thyself"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"Der Challenge Coach","description":"Herausforderungen in Wachstum und Erfolg verwandeln","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"Der Challenge Coach","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]},{"@type":"Person","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0","name":"Pascale Brady","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","caption":"Pascale Brady"},"sameAs":["https:\/\/thechallengecoach.com\/meet-pascale"]}]}},"jetpack_featured_media_url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2024\/05\/hEADER-Copy.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/4315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/comments?post=4315"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/4315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media\/4324"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media?parent=4315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/categories?post=4315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tags?post=4315"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}