{"id":4208,"date":"2023-10-26T14:00:24","date_gmt":"2023-10-26T19:00:24","guid":{"rendered":"https:\/\/thechallengecoach.com\/?p=4208"},"modified":"2023-10-26T14:00:27","modified_gmt":"2023-10-26T19:00:27","slug":"finding-your-ikigai-why-to-get-up-in-the-morning","status":"publish","type":"post","link":"https:\/\/thechallengecoach.com\/de\/finding-your-ikigai-why-to-get-up-in-the-morning","title":{"rendered":"Finde dein IKIGAI: Warum man morgens aufsteht"},"content":{"rendered":"<p><em>Das Thema dieses Newsletters ist Zweck und Sinn.<br>Ich verstehe, dass es angesichts dessen, was derzeit in der Welt vor sich geht, unangemessen erscheinen mag.<br>Ich kann Ihnen versichern, dass ich nicht tonlos bin, und ich m\u00f6chte mir einen Moment Zeit nehmen, um f\u00fcr den FRIEDEN einzutreten, bevor wir beginnen: Ich bin entschieden gegen jede Art von Gewalt gegen unschuldige Zivilisten, ob sie nun von terroristischen Gruppen oder von legitimen Regierungen ausge\u00fcbt wird. Meiner Ansicht nach gibt es keine Rechtfertigung f\u00fcr Gewalt gegen Menschen, niemals.\u00a0<br>Unter diesen Umst\u00e4nden Sinn zu finden, mag aussichtslos erscheinen - und doch glaube ich auch, dass wir es den Leidenden schuldig sind, die gute Arbeit, die wir in diesem Leben leisten, fortzusetzen - die besten Menschen zu sein, die wir sein k\u00f6nnen, damit wir etwas tun k\u00f6nnen, um zu helfen.\u00a0<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"837\" height=\"543\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi.png\" alt=\"\" class=\"wp-image-4217\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi.png 837w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi-300x195.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi-768x498.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi-18x12.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi-570x370.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikagi-600x389.png 600w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n<\/div>\n\n\n<p>Warum sind Sie heute Morgen aufgestanden? Hatten Sie einen zwingenden Grund? Und werden Sie morgen wieder einen zwingenden Grund haben, aufzustehen? N\u00e4chste Woche? N\u00e4chstes Jahr? Wie sieht es aus, wenn Sie 95 Jahre alt sind?<br><br>Als Coach komme ich oft zu den Menschen, um sie dabei zu unterst\u00fctzen, ihrem Leben einen Sinn zu geben. Sie wollen daran arbeiten, ihre Bestimmung zu finden - in der Regel durch die Suche nach Aktivit\u00e4ten, die ihnen ein Gef\u00fchl der Erf\u00fcllung und ein profitables Leben garantieren. Ich helfe meinen Kunden, Ziele f\u00fcr sich zu definieren. Unsere Coaching-Arbeit ist zielorientiert, und eine der Fragen, die ich in meinem \u201cEntdeckungsfragebogen\u201d zu Beginn eines neuen Coachings stelle, lautet: \u201cWenn Sie am Ende Ihres Lebens zur\u00fcckblicken, was m\u00f6chten Sie sehen, und was m\u00f6chten Sie nicht bereuen?\u201d.<br><br>Nat\u00fcrlich war ich begeistert, als ich IKIGAI entdeckte, das japanische Konzept, das \u00fcbersetzt \u201cLebenswert\u201d bedeutet. <strong><em>Ikigai<\/em><\/strong> (\u751f\u304d\u7532\u6590, w\u00f6rtlich 'Grund des Seins') stammt aus der Heian-Periode (zwischen 794 und 1185!) und bezieht sich auf etwas, das einer Person einen Sinn gibt, einen Grund zu leben. Im M\u00e4rz 2021 wurde ich zum zertifizierten <a href=\"https:\/\/thechallengecoach.com\/de\/joue-ta-vie-ikigai\/\">Joue Ta Vie Ikigai Trainer<\/a> und begann, diese Arbeit in mein Coaching einzubeziehen.<\/p>\n\n\n\n<p>Au\u00dferhalb Japans wird das Konzept des ikigai immer mit dem Venn-Diagramm assoziiert, das aus vier sich \u00fcberschneidenden Kreisen besteht:<\/p>\n\n\n\n<p>1) Was Sie lieben<br>2) Was Sie gut k\u00f6nnen<br>3) Wof\u00fcr Sie bezahlt werden k\u00f6nnen<br>4) Was die Welt braucht<\/p>\n\n\n\n<p>Im Schnittpunkt der vier Kreise steht das Wort ikigai.<\/p>\n\n\n\n<p>Diese visuelle Darstellung soll einen Fahrplan f\u00fcr die Suche nach Ihrem ikigai (auch \u201cZweck\u201d genannt) bieten und zeigt, dass Sie nur dann ein echtes ikigai (auch \u201cSinn\u201d genannt) erreichen k\u00f6nnen, wenn alle vier Elemente erf\u00fcllt sind.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"456\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-venn-diagram.png\" alt=\"\" class=\"wp-image-4209\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-venn-diagram.png 513w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-venn-diagram-300x267.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-venn-diagram-14x12.png 14w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/><\/figure>\n<\/div>\n\n\n<p>Trotz seiner anhaltenden Popularit\u00e4t au\u00dferhalb Japans reduziert die Interpretation von ikigai als Venn-Diagramm das japanische Konzept auf ein einziges monumentales Lebensziel, das es zu erreichen gilt. Ikigai umfasst jedoch viel mehr und ist in vielerlei Hinsicht das Gegenteil von dieser Vorstellung. Ikigai ist m\u00f6glich, ohne dass man im Berufsleben erfolgreich sein muss. Bei Ikigai geht es nicht um finanzielle Freiheit; es geht um <strong>Erreichen eines Geisteszustandes, in dem man frei und zielgerichtet leben kann<\/strong>Es geht mehr um Hingabe und die akribische Aus\u00fcbung einer T\u00e4tigkeit als um das, was man von Natur aus schon gut kann. Viele Japaner haben besondere F\u00e4higkeiten und Talente, die wenig oder gar kein Geld einbringen, aber die Erf\u00fcllung, die sie in ihrem Handwerk erreichen, ist unvergleichlich. Dieses Ma\u00df an Beherrschung erfordert Konzentration, Prozess, Disziplin, Achtsamkeit und Liebe zum Detail. Das Erreichen dieses Niveaus der Meisterschaft ist jedoch kein un\u00fcberwindbares und stressiges Ziel: Im Gegenteil, das innere Wesen ist in Frieden und die intrinsische Motivation, dieses Plateau der Kunstfertigkeit zu erreichen, steigt, was wiederum Gef\u00fchle der Vollendung und Erf\u00fcllung freisetzt (mit anderen Worten Dopamin- und Endorphin-Hormone - die \u201cWohlf\u00fchl-\u201d und \u201cGl\u00fcckshormone\u201d). Aus diesem Grund ziehen sich viele Japaner nicht aus dem Berufsleben zur\u00fcck. Sie machen einfach weiter mit der Arbeit, die sie lieben, solange sie gesund sind ... und sie sind gesund!<br>\u00a0<br>Der National Geographic-Reporter Dan Buettner hat bei seinen Recherchen \u00fcber die \u201cblauen Zonen\u201d - geografische Gebiete auf der Welt mit einer h\u00f6heren Lebenserwartung als anderswo - einen Zusammenhang zwischen Ikigai und Langlebigkeit festgestellt. Studien haben gezeigt, dass Menschen, die kein Ikigai empfinden, eher unverheiratet sind, arbeitslos sind, ein niedrigeres Bildungsniveau haben, sich in einem schlechten oder schlechten Gesundheitszustand befinden, ein hohes Ma\u00df an wahrgenommenem psychischem Stress haben, schwere bis mittelschwere K\u00f6rperschmerzen haben und h\u00e4ufiger an Herz-Kreislauf-Erkrankungen leiden.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Habe ich Sie schon \u00fcberzeugt, ikigai ein bisschen mehr in Ihr Leben zu bringen?<\/strong><\/h2>\n\n\n\n<p>\u00a0<br>Obwohl es kein \u201cVenn-Diagramm-Rezept\u201d f\u00fcr Ikigai gibt, haben einige dar\u00fcber geforscht und geschrieben, und Ken Mogi's <em>Kleines Buch des Ikigai<\/em> beschreibt es sehr detailliert. Er hat sogar die folgenden f\u00fcnf n\u00fctzlichen S\u00e4ulen des Ikigai aufgestellt:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"543\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-1024x543.png\" alt=\"\" class=\"wp-image-4210\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-1024x543.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-300x159.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-768x407.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-18x10.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-570x302.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars-600x318.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Pillars.png 1038w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Lassen Sie uns diese ein wenig n\u00e4her betrachten!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-1024x536.png\" alt=\"\" class=\"wp-image-4211\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>PILLAR 1: Klein anfangen<\/strong><\/h1>\n\n\n\n<p><strong>Achten Sie auf die kleinen Details und gehen Sie in kleinen Schritten auf Ihr Ziel zu.<\/strong><\/p>\n\n\n\n<p>Desmond Tutu hat einmal weise gesagt: \u201cEs gibt nur einen Weg, einen Elefanten zu essen: <strong>ein Bissen nach dem anderen<\/strong>.\u201d Das ist ziemlich krass, wenn Sie mich fragen. Aber was er damit meinte, ist, dass alles im Leben, was be\u00e4ngstigend, \u00fcberw\u00e4ltigend und sogar unm\u00f6glich erscheint, schrittweise erreicht werden kann, indem man sich immer nur ein wenig vornimmt. Das Gleiche gilt f\u00fcr die S\u00e4ule 1 von ikigai: Gehen Sie in kleinen Schritten auf Ihre Ziele zu, achten Sie genau auf die kleinen Details, und dann ist es ein f\u00fcr alle Mal vorbei mit der Prokrastination!<\/p>\n\n\n\n<p>FRAGEN, DIE SIE SICH STELLEN SOLLTEN:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Was ist Ihr aktuelles Ziel?<\/li><li>Wie k\u00f6nnen Sie Ihr Ziel in kleine Schritte unterteilen?<\/li><li>Was ist ein erster Schritt, den Sie heute tun k\u00f6nnen?<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-1024x536.png\" alt=\"\" class=\"wp-image-4212\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/2.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>PILLE 2: Sich selbst befreien<\/strong><\/h1>\n\n\n\n<p><strong>Sich selbst zu akzeptieren ist eine der leichtesten, einfachsten und lohnendsten Dinge, die man f\u00fcr sich selbst tun kann.<\/strong><\/p>\n\n\n\n<p>Der erste Schritt zur Selbstakzeptanz besteht darin, sich selbst zu kennen. Wie gut kennen Sie sich selbst? (Wenn nicht, gibt es einen Coach daf\u00fcr&nbsp;<a href=\"https:\/\/emojipedia.org\/winking-face\">\ud83d\ude09<\/a>) Selbsterkenntnis und Bewusstsein sind die ersten Schritte zur Erleuchtung. Wie k\u00f6nnen wir uns selbst ohne Selbsterkenntnis akzeptieren?<br><br>Der zweite Schritt besteht darin, sich selbst gegen\u00fcber liebevoll und mitf\u00fchlend zu sein: Wir sind unser eigener schlimmster Kritiker, und die Stimme in unserem Kopf ist gew\u00f6hnlich die gemeinste von allen.<\/p>\n\n\n\n<p>Versuchen Sie <a href=\"https:\/\/www.youtube.com\/watch?v=EQZ7FN9RFv0&amp;t=6s\">die Meditation der Liebenden G\u00fcte (auch \u201cMetta\u201d genannt)<\/a> wenn Sie dabei Hilfe brauchen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-1024x536.png\" alt=\"\" class=\"wp-image-4213\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/3.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>PILAR 3: Harmonie und Nachhaltigkeit<\/strong><\/h1>\n\n\n\n<p><strong>Nehmen Sie R\u00fccksicht auf Ihre Mitmenschen und achten Sie darauf, wie Sie auf andere und die Gesellschaft wirken.<\/strong><\/p>\n\n\n\n<p>Ikigai-Arbeit ist eine tiefgehende und intime Arbeit. Sie ist mit einer inneren Dimension verbunden, aber sie ist nicht egozentrisch. Es geht um einen Beitrag f\u00fcr die Welt und einen Beitrag f\u00fcr andere: Es geht um einen Sinn f\u00fcr Gemeinschaft. Es ist eine pers\u00f6nliche und intime Suche nach <strong>eine Verbesserung der eigenen Person zum Wohle der Allgemeinheit.<\/strong><\/p>\n\n\n\n<p>FRAGEN, DIE SIE SICH STELLEN SOLLTEN:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Achten Sie normalerweise auf Ihren pers\u00f6nlichen\/beruflichen Einfluss auf die Gesellschaft\/andere?<\/li><li>Ist es etwas, das Ihnen wichtig ist? Was sind Ihre Werte in diesem Bereich?\u00a0<\/li><li>Wie \u00fcberwachen Sie diese Auswirkungen?\u00a0<\/li><li>Ist es jemals in Ordnung, die Werte von Harmonie und Nachhaltigkeit zu verletzen? Wenn ja, unter welchen Umst\u00e4nden? Wann ist es in Ordnung, egoistisch zu sein?\u00a0<\/li><li>Welche Auswirkungen k\u00f6nnte es haben, wenn die Mehrheit der Menschen dieses Ikigai-Prinzip nicht lebt?\u00a0<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-1024x536.png\" alt=\"\" class=\"wp-image-4214\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/4.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>PILLAR 4: Die Freude an kleinen Dingen<\/strong><\/h1>\n\n\n\n<p><strong>Bauen Sie kleine Gl\u00fccksmomente in Ihren Tagesablauf ein. Die Freude muss nicht riesig sein.<\/strong><\/p>\n\n\n\n<p>Jeder, der mich kennt, hat mich schon einmal sagen h\u00f6ren: \u201cEs sind die kleinen Dinge im Leben...\u201d. Das kommt normalerweise, wenn jemand strahlend eine Geschichte der Dankbarkeit oder Wertsch\u00e4tzung f\u00fcr eine kleine Sache, ein Ereignis oder eine Begegnung erz\u00e4hlt, die ihm gerade passiert ist. Einige Beispiele:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Meine erste Tasse Kaffee heute Morgen um 6 Uhr, als ich anfing, diesen Newsletter zu schreiben, war der reine Himmel.<\/li><li>Heute Morgen lie\u00df mich jemand auf eine Fahrspur, ohne dass ich darum k\u00e4mpfen musste - es war so friedlich.<\/li><li>Ich habe gerade eine kleine Pause auf meiner Terrasse eingelegt und diese Fotos von den Blumen in unseren T\u00f6pfen gemacht (keine ist gr\u00f6\u00dfer als ein Zehncentst\u00fcck)<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"254\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-1024x254.jpg\" alt=\"\" class=\"wp-image-4215\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-1024x254.jpg 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-300x74.jpg 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-768x190.jpg 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-18x4.jpg 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-570x141.jpg 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers-600x149.jpg 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Flowers.jpg 1149w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>FRAGEN, DIE SIE SICH STELLEN SOLLTEN:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Was sind die kleinen Dinge, die Ihnen Freude bereiten?\u00a0<\/li><li>Worauf richten Sie Ihre Aufmerksamkeit, wenn Sie durch Ihren Tag gehen?<\/li><li>Werden Sie die kleinen Dinge wahrnehmen, wenn sie vor Ihnen liegen, oder k\u00f6nnten Sie sie \u00fcbersehen?<\/li><li>Wie k\u00f6nnen Sie Ihre Achtsamkeit steigern?<\/li><li>Wie k\u00f6nnen Sie die Freude an den kleinen Dingen des Lebens steigern?<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-1024x536.png\" alt=\"\" class=\"wp-image-4216\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-1024x536.png 1024w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-300x157.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-768x402.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-570x298.png 570w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5-600x314.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/5.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>PILLAR 5: Im Hier und Jetzt sein<\/strong><\/h1>\n\n\n\n<p><strong>Bringen Sie Ihr inneres Kind zum Vorschein, indem Sie im Augenblick pr\u00e4sent sind, anstatt sich an die Vergangenheit oder die Zukunft zu klammern.<\/strong><\/p>\n\n\n\n<p>Als ich vor 18 Jahren am CTI (Coactive Training Institute) die Ausbildung zum Coach absolvierte, wurde uns das \u201cProzess-Coaching\u201d beigebracht, bei dem es darum geht, unseren Kunden zu helfen, ihre Lebenserfahrungen zu verarbeiten, w\u00e4hrend sie geschehen, anstatt sie zu besch\u00f6nigen. Im Hier und Jetzt zu sein bedeutet, nicht mit Bedauern, Schuldgef\u00fchlen oder Scham in der Vergangenheit zu leben, oder in der Zukunft nicht mit Angst, Sorgen und \u00c4ngsten zu leben. Die meisten Menschen wissen nicht, wie sie einfach hier und jetzt, im gegenw\u00e4rtigen Moment, bleiben k\u00f6nnen, vor allem, wenn der gegenw\u00e4rtige Moment unangenehm ist. Und doch ... gibt es nichts anderes, was real und wahr ist, als DIESER Moment. Genau jetzt. W\u00e4hrend Sie dies lesen. Im Hier und Jetzt zu sein, ist eine Frage der Achtsamkeitspraxis, die viele, wenn nicht sogar die meisten Schmerzen des Lebens lindern kann.<\/p>\n\n\n\n<p>Es gibt eine Vielzahl von Programmen oder Apps, die Ihnen helfen k\u00f6nnen, Ihre Achtsamkeit und Meditation zu verbessern. Als zertifizierter Coach f\u00fcr Positive Intelligenz kann ich Ihnen ein Programm anbieten und Sie durch <a href=\"https:\/\/thechallengecoach.com\/de\/positive-intelligence-training\/\">wirkungsvolles 7-w\u00f6chiges Achtsamkeitsprogramm, das Leben und Gehirn ver\u00e4ndert<\/a>.<\/p>\n\n\n\n<p>Zusammenfassend l\u00e4sst sich sagen, dass Ikigai auf eine Geisteshaltung verweist, die den Betroffenen das Gef\u00fchl gibt, ein gl\u00fcckliches und aktives Leben f\u00fchren zu k\u00f6nnen. Es ist in gewissem Sinne ein Barometer, das die Lebenseinstellung einer Person in integrierter und repr\u00e4sentativer Weise widerspiegelt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ikigai gibt Ihrem Leben einen Sinn und gibt Ihnen gleichzeitig den Mut, weiterzumachen.<\/strong><\/h2>\n\n\n\n<p>Ikigai zu haben, kann Ihr Leben buchst\u00e4blich ver\u00e4ndern. Sie k\u00f6nnen l\u00e4nger leben, haben eine gute Gesundheit, sind gl\u00fccklicher, zufriedener und weniger gestresst. Ich hoffe, ich konnte Sie motivieren, an den 5 S\u00e4ulen zu arbeiten und ein wenig mehr ikigai in Ihr Leben zu bringen!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JOUE TA VIE IKIGAI<\/h2>\n\n\n\n<p>Das Ikigai-Coaching \u201cJoue ta Vie\u201d (Spiel dein Leben) basiert auf einem introspektiven Prozess und dem Einsatz von spielerischen und intuitiven Werkzeugen. Es ist sehr effektiv in der Unterst\u00fctzung:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Menschen auf der Suche nach Sinn.<\/li><li>Teenager, die \u00fcber ihre Orientierung nachdenken.<\/li><li>Erwachsene in beruflicher Umschulung.<\/li><li>Arbeitnehmer bei der Arbeit.<\/li><\/ul>\n\n\n\n<p>Es eignet sich perfekt, um mit dem inneren Kind in Kontakt zu treten, Talente zu erkennen, die eigenen Werte zu erkennen, Potenziale zu entwickeln oder eine Kompetenzbilanz zu bereichern. Sie hilft kraftvoll, das Selbstvertrauen zu st\u00e4rken und den Abschluss eines Projekts zu beschleunigen.<\/p>\n\n\n\n<p>WIE ES FUNKTIONIERT<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Das Coaching wird in 2 Stunden abgehalten.<\/li><li>Kosten: $399. Code verwenden <strong>IKIGAI25 f\u00fcr einen Rabatt von 25%<\/strong> als Dankesch\u00f6n f\u00fcr das Lesen meines Newsletters!<\/li><li>Die Betreuung ist ganzheitlich: Sie behandelt gleichzeitig K\u00f6rper und Geist, was ein tiefes Gef\u00fchl des Wohlbefindens und der Zufriedenheit erzeugt.<\/li><li>Dieses Modell des spirituellen Coachings basiert auf den Grundlagen der Neurowissenschaften, der positiven Psychologie und der weniger bekannten Str\u00f6mung der transpersonalen Psychologie<\/li><\/ul>\n\n\n\n<p><strong>Sind Sie BEREIT, Ihr IKIGAI zu finden?<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/thechallengecoach.com\/de\/joue-ta-vie-ikigai\/\" style=\"background-color:#088483\">Erfahren Sie mehr und melden Sie sich hier an<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>The topic of this newsletter is purpose and meaning.I understand that it might seem tone-deaf to what\u2019s going on in the world right now.I can assure you that I am [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-4208","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-uncategorized","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/de\/finding-your-ikigai-why-to-get-up-in-the-morning\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"The topic of this newsletter is purpose and meaning.I understand that it might seem tone-deaf to what\u2019s going on in the world right now.I can assure you that I am [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/de\/finding-your-ikigai-why-to-get-up-in-the-morning\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T19:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T19:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pascale Brady\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascale Brady\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning\"},\"author\":{\"name\":\"Pascale Brady\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\"},\"headline\":\"Finding your IKIGAI: Why to get up in the morning\",\"datePublished\":\"2023-10-26T19:00:24+00:00\",\"dateModified\":\"2023-10-26T19:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning\"},\"wordCount\":1857,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ikigai-website-featured.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning\",\"name\":\"Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ikigai-website-featured.png\",\"datePublished\":\"2023-10-26T19:00:24+00:00\",\"dateModified\":\"2023-10-26T19:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ikigai-website-featured.png\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ikigai-website-featured.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/finding-your-ikigai-why-to-get-up-in-the-morning#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finding your IKIGAI: Why to get up in the morning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\",\"name\":\"Pascale Brady\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"caption\":\"Pascale Brady\"},\"sameAs\":[\"https:\\\/\\\/thechallengecoach.com\\\/meet-pascale\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/de\/finding-your-ikigai-why-to-get-up-in-the-morning\/","og_locale":"de_DE","og_type":"article","og_title":"Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach","og_description":"The topic of this newsletter is purpose and meaning.I understand that it might seem tone-deaf to what\u2019s going on in the world right now.I can assure you that I am [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/de\/finding-your-ikigai-why-to-get-up-in-the-morning\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","article_published_time":"2023-10-26T19:00:24+00:00","article_modified_time":"2023-10-26T19:00:27+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","type":"image\/png"}],"author":"Pascale Brady","twitter_card":"summary_large_image","twitter_creator":"@pascalebrady","twitter_site":"@pascalebrady","twitter_misc":{"Verfasst von":"Pascale Brady","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#article","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning"},"author":{"name":"Pascale Brady","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0"},"headline":"Finding your IKIGAI: Why to get up in the morning","datePublished":"2023-10-26T19:00:24+00:00","dateModified":"2023-10-26T19:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning"},"wordCount":1857,"commentCount":0,"publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"image":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning","url":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning","name":"Finding your IKIGAI: Why to get up in the morning &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","datePublished":"2023-10-26T19:00:24+00:00","dateModified":"2023-10-26T19:00:27+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/finding-your-ikigai-why-to-get-up-in-the-morning#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Finding your IKIGAI: Why to get up in the morning"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"Der Challenge Coach","description":"Herausforderungen in Wachstum und Erfolg verwandeln","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"Der Challenge Coach","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]},{"@type":"Person","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0","name":"Pascale Brady","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","caption":"Pascale Brady"},"sameAs":["https:\/\/thechallengecoach.com\/meet-pascale"]}]}},"jetpack_featured_media_url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/10\/Ikigai-website-featured.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/4208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/comments?post=4208"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/4208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media\/4218"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media?parent=4208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/categories?post=4208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tags?post=4208"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}