{"id":3146,"date":"2021-09-29T11:37:19","date_gmt":"2021-09-29T16:37:19","guid":{"rendered":"https:\/\/thechallengecoach.com\/?p=3146"},"modified":"2021-09-30T09:11:03","modified_gmt":"2021-09-30T14:11:03","slug":"keep-calm-and-carry-on","status":"publish","type":"post","link":"https:\/\/thechallengecoach.com\/de\/keep-calm-and-carry-on","title":{"rendered":"Ruhig bleiben und weitermachen"},"content":{"rendered":"<p>Sie fragen sich vielleicht, warum Sie seit meinem letzten Newsletter vom 27. Mai nichts mehr von mir geh\u00f6rt haben.<br><br>Bevor ich das erkl\u00e4re, m\u00f6chte ich Sie an Folgendes erinnern. Ich bin der Challenge Coach geworden, weil ich ein herausgeforderter Mensch war und immer noch bin. Das Leben stellt uns vor Herausforderungen, wenn wir sie am wenigsten erwarten: Je besser wir darauf vorbereitet sind, desto besser k\u00f6nnen wir mit diesen Herausforderungen des Lebens umgehen. Wenn wir f\u00fcr die Herausforderungen des Lebens trainiert sind, \u00fcberleben wir nicht nur, sondern wir D\u00dcRFEN. In Anbetracht der vielen Herausforderungen, die das Leben mir gestellt hat, f\u00fchle ich mich ziemlich gut ger\u00fcstet, und <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=0976ca7af2&amp;e=1980597a3c\" target=\"_blank\" rel=\"noreferrer noopener\">Ich bin bereit, Ihnen zu helfen<\/a> Bauen Sie Ihren eigenen Werkzeugkasten auf und erweitern Sie ihn.<br><br><strong><span style=\"color:#088483\" class=\"has-inline-color\">Ich m\u00f6chte Sie nun in den Mai 2021 zur\u00fcckversetzen...<\/span><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/May.png\" alt=\"\" class=\"wp-image-3147\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/May.png 250w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/May-100x100.png 100w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/May-150x150.png 150w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/May-12x12.png 12w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><figcaption><span style=\"color:#088483\" class=\"has-inline-color\"><strong>Freitag, 28. Mai 2021 - Milwaukee, Wisconsin<\/strong><\/span><\/figcaption><\/figure><\/div>\n\n\n\n<p>Ich kam am Vortag in Milwaukee an, um an der NASAP-Konferenz (North American Society of Adlerian Psychology) und deren Vorstandssitzung teilzunehmen. Das erste Mal seit 14 Monaten, dass ich aus beruflichen Gr\u00fcnden das Haus verlie\u00df. Und das erste Mal, dass ich bei der NASAP pers\u00f6nlich als Redner auftrat. Ich hatte schon immer an der Konferenz teilgenommen und von den Meistern der Adlerianischen Psychologie \u00fcber die Adlerianische Psychologie gelernt (mehr \u00fcber Alfred Adler und die Adlerianische Psychologie <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=95246ec7b6&amp;e=1980597a3c\" target=\"_blank\" rel=\"noreferrer noopener\">Hier<\/a>). Es ist unn\u00f6tig zu sagen, dass dies eine gro\u00dfe Ehre und eine v\u00f6llig nervenaufreibende Erfahrung war, auf die ich mich monatelang vorbereitet habe. Es waren nicht allzu viele Leute pers\u00f6nlich auf der Konferenz anwesend, aber es war fabelhaft, die Leute wieder \u201clive\u201d zu sehen und mit so vielen alten Freunden oder Kollegen und gesch\u00e4tzten Lehrern und Mentoren wieder zusammenzukommen.&nbsp;<\/p>\n\n\n\n<p>Es ist 4 Uhr morgens am Freitag und ich schlafe in meinem Hotelzimmer, um den dringend ben\u00f6tigten Schlaf zu bekommen, den ich brauche, um meinen ersten Workshop auf der Konferenz zu halten. Ich wache verwirrt auf ... und stelle fest, dass es das Summen meines Telefons war, das mich geweckt hat. Ich schaue es an: Ich habe gerade einen WhatsApp-Anruf von meiner Schwester B\u00e9n\u00e9dicte verpasst. Sie ist in Frankreich, 6 Stunden vor mir, und sie wei\u00df um unseren Zeitunterschied. Wenn sie mich angerufen hat, muss es etwas Ernstes sein.&nbsp;<\/p>\n\n\n\n<p>Ich rufe sie zur\u00fcck. <em>\u201cEs tut mir leid, dass ich dich so fr\u00fch geweckt habe. Ich habe so lange gewartet, wie ich konnte, um dir eine ruhige Nacht zu g\u00f6nnen. Papa ist heute Morgen gestorben.\u201d&nbsp;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/1-1-199x300.jpg\" alt=\"\" data-id=\"3149\" data-full-url=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/1-1.jpg\" data-link=\"https:\/\/thechallengecoach.com\/?attachment_id=3149\" class=\"wp-image-3149\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/1-1-199x300.jpg 199w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/1-1-8x12.jpg 8w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/1-1.jpg 395w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/2-199x300.png\" alt=\"\" data-id=\"3148\" data-full-url=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/2.png\" data-link=\"https:\/\/thechallengecoach.com\/?attachment_id=3148\" class=\"wp-image-3148\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/2-199x300.png 199w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/2-8x12.png 8w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/2.png 395w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Es ist einer dieser Momente, in denen die Zeit stehen bleibt: Alles verlangsamt sich, die Realit\u00e4t wird verzerrt, und man macht eine au\u00dferk\u00f6rperliche Erfahrung. In der einen Minute war diese Person noch da. In der n\u00e4chsten ist sie weg, und das Leben wird nie mehr dasselbe sein.&nbsp;<\/p>\n\n\n\n<p>Meine Schwester und ich unterhalten uns noch ein wenig und sie erz\u00e4hlt mir die Details, die sie wei\u00df. Mein Papa, Philippe, war am Abend zuvor mit seiner Frau zu Hause. Sie machte ihm eines seiner Lieblingsgerichte - Steak und Pommes frites - und sie sahen zusammen einen Film. Er ging zu Bett, wachte ein paar Stunden fr\u00fcher als sonst auf, stand auf und verlie\u00df das Bett ohne seine Kr\u00fccken, ging und setzte sich in seinen Sessel. Innerhalb k\u00fcrzester Zeit h\u00f6rte seine Lunge auf zu arbeiten, sein Herz gab auf und er war tot. Seine Frau wachte auf, als sie ihn nach Luft schnappen h\u00f6rte. Als sie ihn fand, war es bereits zu sp\u00e4t.&nbsp;<br><br>Ich liege im Bett, nachdem ich mit B\u00e9n\u00e9 aufgelegt habe: Sie hat mir gesagt, dass Papa immer noch in seinem Haus in den Vororten von Paris ist. Sie und mein Bruder (die beide weit weg wohnen) werden heute nach Paris kommen, um sich von ihm zu verabschieden, um unsere Stiefmutter Elena zu unterst\u00fctzen und um zu entscheiden, was mit seiner Leiche geschehen soll. Meine Geschwister werden \u00fcber Nacht bleiben und sich am n\u00e4chsten Tag mit dem Bestattungsunternehmen treffen, um alle Vorbereitungen zu treffen.&nbsp;<\/p>\n\n\n\n<p>Es dauert nicht lange, bis ich im Dunkeln in Milwaukee liege und merke, dass ich gehen muss: Ich wei\u00df nicht, wie ich es schaffen werde, aber ich nehme heute Abend einen Flug nach Paris, damit ich mich auch verabschieden kann. Ich werde auf jeden Fall bei ihnen sein, in diesem so wichtigen, aber fl\u00fcchtigen Moment. Es gibt bestimmte Lebensabschnitte, die man nicht verpassen sollte. So beginnt ein absolut verr\u00fcckter Tag, an dem ich auf ein einziges Ziel hinarbeite: den Flug nach Paris in dieser Nacht zu erreichen.&nbsp;<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"523\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go.png\" alt=\"\" class=\"wp-image-3150\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go.png 800w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go-600x392.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go-300x196.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go-768x502.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go-18x12.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Wherever-you-go-570x373.png 570w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Ich springe um 5 Uhr morgens aus dem Bett und finde einen Flug um 7 Uhr zur\u00fcck nach Baltimore. Ich kontaktiere mein \"Life Team\" (Lebenspartnerin und zwei T\u00f6chter) und bitte sie, mir bei der Planung all der anderen Dinge zu helfen, die f\u00fcr den Erfolg dieser Mission erforderlich sind: ein Covid-Schnelltest, ein 72-Stunden-PCR-Covid-Test (die franz\u00f6sischen Vorschriften verlangten damals einen negativen 72-Stunden-Covid-Test, aber ich habe nur 12 Stunden Zeit, bevor ich an Bord gehen muss, also mache ich beide Tests und bete, dass sie eine Ausnahme machen), ein Flugticket nach Paris f\u00fcr diese Nacht und alles andere, was ich vielleicht vergessen habe. Ich schaffe den Flug von Milwaukee nach Baltimore um 7 Uhr morgens und sitze dann nach der Landung eine Stunde lang im Flughafen, um die Buchung des Fluges nach Paris abzuschlie\u00dfen, den eines meiner Kinder f\u00fcr mich gefunden hat. Dann eile ich nach Hause, um herauszufinden, dass meine andere Tochter innerhalb einer Stunde zwei Covid-Tests angesetzt hat und ich mich beeilen muss, wenn ich sie schaffen will (nat\u00fcrlich ist jeder Test in einem anderen Stadtteil). Mitten in all dem stelle ich fest, dass ich keinen Reisepass habe! Er wurde vor ein paar Wochen zur Erneuerung an das Au\u00dfenministerium geschickt. Zwischen den Aufgaben spreche ich mit einem Freund in der franz\u00f6sischen Botschaft, um herauszufinden, ob ich die USA verlassen, nach Frankreich einreisen und dann wieder in die USA zur\u00fcckkehren kann (h\u00f6chstwahrscheinlich nicht). Ich renne zur\u00fcck nach Hause, packe meine Konferenztasche aus und packe einen Koffer f\u00fcr Paris (ohne zu wissen, wie lange ich weg sein werde ...). Kaum ein paar Stunden nach der Landung auf dem Flughafen Baltimore bin ich auf dem Weg zum Flughafen Dulles, um meinen Flug nach Paris zu nehmen. Ich wei\u00df, dass die Wahrscheinlichkeit, dass ich diesen Flug nehmen werde, verschwindend gering ist.&nbsp;<\/p>\n\n\n\n<p>Bei der Abfertigung wird mir die Bef\u00f6rderung verweigert, da ich nicht den erforderlichen 72-Stunden-negativen PCR-Test vorweisen kann. Ich erkl\u00e4re den Leuten, dass mein Vater heute Morgen gestorben ist: Das hilft. Die Menschen k\u00fcmmern sich, und die Menschen sind freundlich. Sie wollen helfen, wenn sie die Chance dazu haben. Wie durch ein Wunder sitzt an Bord desselben Fluges eine Frau, die sich als Engel entpuppt und f\u00fcr die franz\u00f6sische Einwanderungsbeh\u00f6rde arbeitet. Die Flugbegleiter von Air France scheinen sie irgendwie zu kennen, und sie erkl\u00e4rt sich bereit (obwohl sie in ihrer Freizeit unterwegs ist), aus der Reihe zu tanzen und jemanden zu kontaktieren, den sie bei der franz\u00f6sischen Einwanderungsbeh\u00f6rde in Paris kennt ... der ihr sagt, dass sie f\u00fcr mich eine Ausnahme machen k\u00f6nnen und ich nach Frankreich einreisen darf. Sie lassen mich auch ausreisen, obwohl ich meinen US-Pass nicht dabei habe. Ein weiteres Wunder. Allerdings bleibt abzuwarten, wie ich es zur\u00fcck in die USA schaffen werde.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"570\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together.png\" alt=\"\" class=\"wp-image-3151\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together.png 800w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together-600x428.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together-300x214.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together-768x547.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together-18x12.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Together-570x406.png 570w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Einige Stunden sp\u00e4ter heben wir nach Paris ab. Als ich mich in meinem Sitz niederlasse, lasse ich diesen sehr intensiven Tag Revue passieren und z\u00e4hle meine Segnungen.<br><br>In diesem Moment merke ich, dass ich einen Abgabetermin f\u00fcr die Arbeit vergessen habe, den ich heute hatte. Unglaublicherweise hat der Air-France-Flug, in dem ich sitze, WiFi - und ich verbringe die n\u00e4chsten drei Stunden damit, ein gro\u00dfes Projekt per Text auf meinem iPhone fertigzustellen, um meine Frist einzuhalten. Ich schaffe es, und es ist unglaublich!!!<br><br>JETZT kann ich mich endlich ausruhen. Ich schlie\u00dfe die Augen und hole mein Reisekissen heraus: Wir sind seit dreieinhalb Stunden unterwegs. Ich kann immer noch versuchen, meine Augen f\u00fcr die verbleibenden drei Stunden dieses Fluges zu schlie\u00dfen.<br><br>ICH HABE ES GESCHAFFT! Ich werde mich von Papa verabschieden. Ich werde ihn ein letztes Mal sehen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p>In diesem Moment macht der Kapit\u00e4n \u00fcber die Sprechanlage eine verbl\u00fcffende Durchsage: <em>\u201cWir haben einen medizinischen Notfall und kehren um. Wir fliegen zur\u00fcck nach DC.\u201d ...<\/em><\/p>\n\n\n\n<p>DAS ... muss der gr\u00f6\u00dfte kosmische Scherz sein, der jemals jemandem passiert ist. Mein Vater, der einen b\u00f6sen Sinn f\u00fcr Humor hatte, muss sich einen Riesenspa\u00df daraus gemacht haben! Einige Leute um mich herum auf dem Flug sind eindeutig aufgeregt, nerv\u00f6s oder w\u00fctend. Seltsamerweise bleibe ich ganz ruhig. Die beiden Ausdr\u00fccke, die mir in diesem Moment in den Sinn kommen, sind \u201cque sera sera\u201d (was sein wird, wird sein\u201c auf Italienisch) und \u201dInshallah\u201c (so Gott will\u201d auf Arabisch). Es ist ein v\u00f6lliger Verzicht auf Kontrolle: Ich bin in Frieden mit dem Schicksal, und ich bin dankbar, dass ich in Frieden bin.<\/p>\n\n\n\n<p>Schlie\u00dflich landen wir gegen 1 Uhr morgens wieder auf dem Flughafen Dulles. Wie durch ein Wunder lassen sie uns, obwohl wir keinen Pass f\u00fcr die Wiedereinreise haben, wieder in den Flughafen, ohne dass wir auf die Einwanderungsbeh\u00f6rde treffen, da wir mitten in der Nacht in Dulles landen und technisch gesehen das Land nicht wirklich verlassen haben.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><span style=\"color:#088483\" class=\"has-inline-color\">Haben Sie die Anzahl der Wunder gez\u00e4hlt, die an diesem Tag geschehen sind?<\/span><\/strong><\/p>\n\n\n\n<p>Das eigentliche Wunder ist jedoch, dass ich ruhig geblieben bin - den ganzen Tag lang. Ich blieb konzentriert - den ganzen Tag lang. Ich habe geatmet - den ganzen Tag lang. Und das nicht nur, um zu \u00fcberleben, wie wir alle es tun, sondern ganz bewusst, mit Absicht. Ich wusste, wenn ich mein einziges Ziel erreichen wollte, an diesem Tag von Milwaukee nach Paris zu kommen, um meinen Papa zu sehen, musste ich ruhig bleiben und meine Emotionen und meinen Stress im Griff haben, sonst w\u00fcrde ich nicht schaffen, was zu tun war. Ich wusste - denn das ist es, was ich lehre und t\u00e4glich praktiziere -, dass ich es nur schaffen w\u00fcrde, wenn ich ruhig blieb, mich konzentrierte und atmete.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><span style=\"color:#088483\" class=\"has-inline-color\">Lassen Sie mich diese Atem\u00fcbung mit Ihnen teilen.<\/span><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ruhig bleiben und weitermachen\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/mJ-xMvYL6Kg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Das ist viel leichter gesagt als getan, vor allem in Krisenzeiten ... Deshalb muss man sich durch Achtsamkeit und Atmung beruhigen, wenn man sich *nicht* in einer Krise befindet. Es ist ein bisschen so, als w\u00fcrden wir ins Fitnessstudio gehen - mit dem Unterschied, dass es sich hier um das Fitnessstudio des Gehirns handelt: Wir k\u00f6nnen unsere \u201cF\u00e4higkeit, ruhig zu bleiben\u201d in ruhigen Zeiten trainieren, wenn wir sie nicht brauchen, so dass sie uns zur Verf\u00fcgung steht, wenn wir sie brauchen. Glauben Sie mir, wenn ich sage, dass diese Praxis das Leben ver\u00e4ndert (zus\u00e4tzlich zur Ver\u00e4nderung des Gehirns!), und zwar auf zwei Ebenen: 1) weil Sie Ihr Gehirn tats\u00e4chlich so ver\u00e4ndern, dass es besser funktioniert und Ihnen zu Diensten ist (statt dass Sie ihm ausgeliefert sind). Und 2) weil es ein Wunder ist (ein weiteres?), zu erkennen, dass wir tats\u00e4chlich diese Macht \u00fcber uns selbst haben. Wir k\u00f6nnen uns buchst\u00e4blich dazu bringen, eine ANDERE PERSON zu sein. Das ist eine coole Sache, wenn Sie mich fragen.<\/p>\n\n\n\n<p>Ein weiterer Punkt, der in Krisenzeiten hilfreich ist, ist die Tatsache, dass man als einer der <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=93e757a727&amp;e=1980597a3c\" target=\"_blank\" rel=\"noreferrer noopener\">Mamma Jar Notizen<\/a> sagen:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"348\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass.png\" alt=\"\" class=\"wp-image-3152\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass.png 800w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass-600x261.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass-300x131.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass-768x334.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass-18x8.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/This-too-shall-pass-570x248.png 570w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Ich schaffte es schlie\u00dflich nach Frankreich (diesmal mit einem Reisepass!), um 10 Tage sp\u00e4ter an der Trauerfeier f\u00fcr meinen Vater teilzunehmen. Endlich konnte ich mich von ihm verabschieden... es sollte nur nicht das erste Mal sein.<br><br>Ich habe den Sommer in Frankreich verbracht, um mit meiner Familie zu trauern und bei allem zu helfen, was nach dem Tod eines Menschen zu erledigen ist. Wie sich herausstellte, war es ein weiteres Wunder, dass ich auf der anderen Seite des Ozeans war, als meine Tochter, die ein Sommerpraktikum in Spanien absolvierte, an Covid-19 erkrankte. Aber das ist eine Geschichte f\u00fcr ein anderes Mal...<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"412\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens.png\" alt=\"\" class=\"wp-image-3153\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens.png 800w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens-600x309.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens-300x155.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens-768x396.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Everything-happens-570x294.png 570w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p><strong><span style=\"color:#088483\" class=\"has-inline-color\">In memoriam&nbsp;<\/span><\/strong><br><br>Mein Vater, selbst Musiker, war ein gro\u00dfer Bewunderer und Kenner klassischer Musik. Dies war eines seiner Lieblingsst\u00fccke aller Zeiten:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Richard Strauss - Vier Letzte Lieder (Kiri Te Kanawa)\" width=\"1140\" height=\"855\" src=\"https:\/\/www.youtube.com\/embed\/ODwcbNFpifQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Das zweite der vier St\u00fccke hei\u00dft \u201cSeptember\u201d und ist ein Gedicht von Hermann Hesse:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><span style=\"color:#088483\" class=\"has-inline-color\">Der Garten ist in Trauer.<br><em>K\u00fchler Regen sickert in die Blumen.<\/em><br><em>Die Sommerzeit schaudert,<\/em><br><em>Er wartet in aller Ruhe auf sein Ende.<\/em><br><br><em>Ein goldenes Blatt nach dem anderen f\u00e4llt<\/em><br><em>vom hohen Akazienbaum.<\/em><br><em>Summer l\u00e4chelt, erstaunt und schwach,<\/em><br><em>bei seinem sterbenden Traum von einem Garten.<\/em><br><br><em>Nur eine Weile verweilt er&nbsp;<\/em><br><em>neben den Rosen, die sich nach Ruhe sehnen.<\/em><br><em>Langsam schlie\u00dft er die<\/em><br><em>seine m\u00fcden Augen.<\/em><\/span><\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"396\" src=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks.png\" alt=\"\" class=\"wp-image-3154\" srcset=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks.png 800w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks-600x297.png 600w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks-300x149.png 300w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks-768x380.png 768w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks-18x9.png 18w, https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/Music-speaks-570x282.png 570w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>Sind Sie bereit zu wachsen und Ihren Werkzeugkasten zu erweitern, um die Herausforderungen des Lebens zu meistern? Vielleicht haben Sie auch k\u00fcrzlich jemanden verloren, der Ihnen nahe stand, und brauchen Hilfe bei der Verarbeitung der Trauer? Ich bin hier, um zu helfen!<br><br>Buchen Sie eine <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=5fb7cc5c66&amp;e=1980597a3c\" target=\"_blank\" rel=\"noreferrer noopener\">kostenlose Probe-Coaching-Sitzung<\/a> hier, oder <a href=\"https:\/\/thechallengecoach.us14.list-manage.com\/track\/click?u=e2a090dacf09a83346da8dac7&amp;id=7dfbfda8e4&amp;e=1980597a3c\" target=\"_blank\" rel=\"noreferrer noopener\">indem Sie einfach in Kontakt kommen<\/a> um mehr zu erfahren.<\/p>","protected":false},"excerpt":{"rendered":"<p>You may be wondering why you haven\u2019t heard from me since my last newsletter on May 27. Before I explain, I want to remind you of this. I became The [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":3140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-3146","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-uncategorized","8":"czr-hentry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Keep Calm and Carry On &#8211; The Challenge Coach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thechallengecoach.com\/de\/keep-calm-and-carry-on\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keep Calm and Carry On &#8211; The Challenge Coach\" \/>\n<meta property=\"og:description\" content=\"You may be wondering why you haven\u2019t heard from me since my last newsletter on May 27. Before I explain, I want to remind you of this. I became The [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thechallengecoach.com\/de\/keep-calm-and-carry-on\/\" \/>\n<meta property=\"og:site_name\" content=\"The Challenge Coach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-29T16:37:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T14:11:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pascale Brady\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:site\" content=\"@pascalebrady\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pascale Brady\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on\"},\"author\":{\"name\":\"Pascale Brady\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\"},\"headline\":\"Keep Calm and Carry On\",\"datePublished\":\"2021-09-29T16:37:19+00:00\",\"dateModified\":\"2021-09-30T14:11:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on\"},\"wordCount\":2075,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AdobeStock_324490808-Copy-scaled.jpeg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on\",\"name\":\"Keep Calm and Carry On &#8211; The Challenge Coach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AdobeStock_324490808-Copy-scaled.jpeg\",\"datePublished\":\"2021-09-29T16:37:19+00:00\",\"dateModified\":\"2021-09-30T14:11:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#primaryimage\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AdobeStock_324490808-Copy-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/AdobeStock_324490808-Copy-scaled.jpeg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/keep-calm-and-carry-on#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thechallengecoach.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keep Calm and Carry On\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#website\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"name\":\"The Challenge Coach\",\"description\":\"Transforming challenges into growth and success\",\"publisher\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thechallengecoach.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#organization\",\"name\":\"The Challenge Coach\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"contentUrl\":\"https:\\\/\\\/thechallengecoach.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/The-Challenge-Coach-logo-RGB-small.jpg\",\"width\":600,\"height\":179,\"caption\":\"The Challenge Coach\"},\"image\":{\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pascale.Brady.TheChallengeCoach\",\"https:\\\/\\\/x.com\\\/pascalebrady\",\"https:\\\/\\\/instagram.com\\\/the_challenge_coach\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/TheChallengeCoach\",\"https:\\\/\\\/www.pinterest.com\\\/globallifecoach\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thechallengecoach.com\\\/#\\\/schema\\\/person\\\/be56ccf965a222983ad0566a84e41fe0\",\"name\":\"Pascale Brady\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g\",\"caption\":\"Pascale Brady\"},\"sameAs\":[\"https:\\\/\\\/thechallengecoach.com\\\/meet-pascale\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Keep Calm and Carry On &#8211; The Challenge Coach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thechallengecoach.com\/de\/keep-calm-and-carry-on\/","og_locale":"de_DE","og_type":"article","og_title":"Keep Calm and Carry On &#8211; The Challenge Coach","og_description":"You may be wondering why you haven\u2019t heard from me since my last newsletter on May 27. Before I explain, I want to remind you of this. I became The [&hellip;]","og_url":"https:\/\/thechallengecoach.com\/de\/keep-calm-and-carry-on\/","og_site_name":"The Challenge Coach","article_publisher":"https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","article_published_time":"2021-09-29T16:37:19+00:00","article_modified_time":"2021-09-30T14:11:03+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","type":"image\/jpeg"}],"author":"Pascale Brady","twitter_card":"summary_large_image","twitter_creator":"@pascalebrady","twitter_site":"@pascalebrady","twitter_misc":{"Verfasst von":"Pascale Brady","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#article","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on"},"author":{"name":"Pascale Brady","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0"},"headline":"Keep Calm and Carry On","datePublished":"2021-09-29T16:37:19+00:00","dateModified":"2021-09-30T14:11:03+00:00","mainEntityOfPage":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on"},"wordCount":2075,"commentCount":0,"publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"image":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on","url":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on","name":"Keep Calm and Carry On &#8211; The Challenge Coach","isPartOf":{"@id":"https:\/\/thechallengecoach.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#primaryimage"},"image":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#primaryimage"},"thumbnailUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","datePublished":"2021-09-29T16:37:19+00:00","dateModified":"2021-09-30T14:11:03+00:00","breadcrumb":{"@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thechallengecoach.com\/keep-calm-and-carry-on"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#primaryimage","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/thechallengecoach.com\/keep-calm-and-carry-on#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thechallengecoach.com\/"},{"@type":"ListItem","position":2,"name":"Keep Calm and Carry On"}]},{"@type":"WebSite","@id":"https:\/\/thechallengecoach.com\/#website","url":"https:\/\/thechallengecoach.com\/","name":"Der Challenge Coach","description":"Herausforderungen in Wachstum und Erfolg verwandeln","publisher":{"@id":"https:\/\/thechallengecoach.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thechallengecoach.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thechallengecoach.com\/#organization","name":"Der Challenge Coach","url":"https:\/\/thechallengecoach.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/","url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","contentUrl":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2023\/02\/The-Challenge-Coach-logo-RGB-small.jpg","width":600,"height":179,"caption":"The Challenge Coach"},"image":{"@id":"https:\/\/thechallengecoach.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pascale.Brady.TheChallengeCoach","https:\/\/x.com\/pascalebrady","https:\/\/instagram.com\/the_challenge_coach","https:\/\/www.linkedin.com\/in\/TheChallengeCoach","https:\/\/www.pinterest.com\/globallifecoach"]},{"@type":"Person","@id":"https:\/\/thechallengecoach.com\/#\/schema\/person\/be56ccf965a222983ad0566a84e41fe0","name":"Pascale Brady","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d0b27cf09078d44de7bc8e157eb703a5c18dfeefd42c886050875912dfa1879?s=96&d=mm&r=g","caption":"Pascale Brady"},"sameAs":["https:\/\/thechallengecoach.com\/meet-pascale"]}]}},"jetpack_featured_media_url":"https:\/\/thechallengecoach.com\/wp-content\/uploads\/2021\/09\/AdobeStock_324490808-Copy-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/3146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/comments?post=3146"}],"version-history":[{"count":0,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/posts\/3146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media\/3140"}],"wp:attachment":[{"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/media?parent=3146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/categories?post=3146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thechallengecoach.com\/de\/wp-json\/wp\/v2\/tags?post=3146"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}